
{"id":3420,"date":"2021-11-18T15:04:20","date_gmt":"2021-11-18T15:04:20","guid":{"rendered":"https:\/\/staging.novelis.io\/?page_id=3420"},"modified":"2025-10-06T09:42:00","modified_gmt":"2025-10-06T09:42:00","slug":"accueil","status":"publish","type":"page","link":"https:\/\/novelis.io\/fr\/","title":{"rendered":"Page d&rsquo;accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3420\" class=\"elementor elementor-3420 elementor-21\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0557fb1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0557fb1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60e37af\" data-id=\"60e37af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e76c8d0 elementor-widget elementor-widget-header\" data-id=\"e76c8d0\" data-element_type=\"widget\" data-widget_type=\"header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t      <script>\n\t\t const debugSectionTracker = \"no\";\n        autoRedirectPrefLang();\n      <\/script>\n      <header id=\"header\" class=\"header position-fixed w-100\">\n        <div>\n          <div  id=\"nav_header\" class=\"nav_header_container shadow-sm nav_header\">\n            <div class=\"nav_secondary container-fluid d-flex justify-content-end align-items-center nav_secondary_white_color\" id=\"nav_secondary\">\n                \n                <!-- start -->\n                                    <div class=\"px-1 pt-2 pb-0 bd-highlight\"><a href=\"https:\/\/www.linkedin.com\/company\/novelis-consulting\/\" class=\"socials_color\" target=\"_blank\" rel=\"noopener\">\n                              <i class=\"bi bi-linkedin\"><\/i>\n                            <\/a><\/div>\n\n                                    <div class=\"px-1 pt-2 pb-0 bd-highlight\"><a href=\"https:\/\/x.com\/novelis_io\" class=\"socials_color\">\n                            <svg width=\"1200\" height=\"1227\" viewBox=\"0 0 1200 1227\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" style=\"\n      vertical-align: -.125em;\n      height: 1em;\n      width: 1em;\n  \">\n  <path d=\"M714.163 519.284L1160.89 0H1055.03L667.137 450.887L357.328 0H0L468.492 681.821L0 1226.37H105.866L515.491 750.218L842.672 1226.37H1200L714.137 519.284H714.163ZM569.165 687.828L521.697 619.934L144.011 79.6944H306.615L611.412 515.685L658.88 583.579L1055.08 1150.3H892.476L569.165 687.854V687.828Z\" fill=\"currentColor\"><\/path>\n  <\/svg>\n                \n                            <\/a><\/div>\n\n                                    <div class=\"px-1 pt-2 pb-0 bd-highlight\"><a href=\"https:\/\/www.youtube.com\/channel\/UCJ5eJR22n2GtfKaTWueWRPQ\" class=\"socials_color\" target=\"_blank\" rel=\"noopener\">\n                              <i class=\"bi bi-youtube\"><\/i>\n                            <\/a><\/div>\n\n                                <!-- end -->\n                <div class=\"px-1 pt-2 pb-0 bd-highlight d-none\">\n                  <div class=\"dropdown\">\n                    <button class=\"btn btn-outline-light btn-sm dropdown-toggle button_color\" id=\"nav_secondary_dropdown\" type=\"button\" data-bs-toggle=\"dropdown\" aria-expanded=\"false\">\n                      Nos produits                    <\/button>\n                    \n                    <ul class=\"dropdown-menu dropdown-menu-end\" aria-labelledby=\"dropdownMenuButton1\">\n\n                                                \n                            <li>\n                              <a class=\"dropdown-item\" target=\"_blank\" href=\"https:\/\/smartroby.com\/\" rel=\"noopener\">SmartRoby\u00ae<\/a>\n                            <\/li>\n                            \n                                                        \n                            <li>\n                              <a class=\"dropdown-item\" target=\"_blank\" href=\"https:\/\/novypom.com\/\" rel=\"noopener\">Novy POM<\/a>\n                            <\/li>\n                            \n                                                        \n                            <li>\n                              <a class=\"dropdown-item\" target=\"_blank\" href=\"https:\/\/novelis.io\/fr\/work\/eshadow-proteger-vos-donnees-avec-la-solution-de-pseudonymisation-et-danonymisation-des-documents-la-plus-avancee\/\">eShadow<\/a>\n                            <\/li>\n                            \n                                                        \n                            <li>\n                              <a class=\"dropdown-item\" target=\"_blank\" href=\"https:\/\/novelis.io\/fr\/work\/esummarize-le-moteur-de-resume-de-documents-a-base-de-lintelligence-artificielle\/\">eSummarize<\/a>\n                            <\/li>\n                            \n                                                <\/ul>\n                  <\/div>\n                <\/div>\n            <\/div>\n            <nav class=\"nav_primary navbar navbar-expand-lg navbar-light\"  id=\"nav_primary\">\n              <div class=\"container-fluid\">\n                <a class=\"mx-3 nav_logo_container position-relative\" href=\"https:\/\/novelis.io\/fr\/\">\n                  <div class=\"nav_logo position-relative\" id=\"nav_logo_white\" style=\"content: url(https:\/\/novelis.io\/wp-content\/uploads\/2021\/12\/light_logo.png)\"><\/div>\n                  <div class=\"nav_logo position-absolute top-0\" id=\"nav_logo_colorful\" style=\"content: url(https:\/\/novelis.io\/wp-content\/uploads\/2021\/12\/logo-1.png)\"><\/div>\n                <\/a>\n                <button type=\"button\" class=\"nav-item search_buttons ms-auto me-1 d-block d-lg-none btn navbar_transparent_button\">\n                  <i class=\"bi bi-search\"><\/i>\n                <\/button>\n                <button id=\"navbar_toggler\" class=\"nav-item navbar_transparent_button navbar-toggler border-0\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#navbarSupportedContent\" aria-controls=\"navbarSupportedContent\" aria-expanded=\"false\" aria-label=\"Toggle navigation\">\n                  <span class=\"navbar-toggler-icon\"><\/span>\n                <\/button>\n                <div class=\"pt-lg-0 collapse navbar-collapse\" id=\"navbarSupportedContent\">\n\n                  <div class=\"pt-2 accordion accordion-flush d-block d-lg-none\" id=\"accordionFlushExample\">\n\n                    \n                            <div class=\"accordion-item overflow-hidden\">\n                              <div class=\"accordion-header\" id=\"flush-heading1720\">\n                                 \n                                  <a  class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-collapse1720\" aria-expanded=\"false\" aria-controls=\"flush-collapse1720\">\n                                  <span>Services<\/span>\n\n                                  <\/a>\n                                                              <\/div>\n                              \n                              <div id=\"flush-collapse1720\" class=\"accordion-collapse collapse\" aria-labelledby=\"flush-heading1720\" data-bs-parent=\"#accordionFlushExample\">\n                                <ul class=\"accordion-body collapse_body_items pt-0\">\n                                  \n                                  <a href=\"https:\/\/novelis.io\/expertise\/\" class=\"py-2 px-4 mobile-nav-item \">Services<\/a>\n                                                                      <a href=\"https:\/\/novelis.io\/expertises\/automation-rpa-process-mining\/\" class=\"py-2 px-4 mobile-nav-item \">Intelligent Automation<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/expertises\/artificial-intelligence\/\" class=\"py-2 px-4 mobile-nav-item \">Artificial Intelligence and GenAI<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/expertises\/process-intelligence\/\" class=\"py-2 px-4 mobile-nav-item \">Process Intelligence<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/expertises\/innovative-architecture\/\" class=\"py-2 px-4 mobile-nav-item \">Innovative Architectures<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/expertises\/cybersecurity\/\" class=\"py-2 px-4 mobile-nav-item \">Cybersecurity<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/business-cases\/\" class=\"py-2 px-4 mobile-nav-item \">Business Cases<\/a>\n                                                                      \n                                <\/ul>\n                              <\/div>\n                                                          <\/div>\n\n                          \n\n                    \n                            <div class=\"accordion-item overflow-hidden\">\n                              <div class=\"accordion-header\" id=\"flush-heading8858\">\n                                 \n                                  <a  class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-collapse8858\" aria-expanded=\"false\" aria-controls=\"flush-collapse8858\">\n                                  <span>Products<\/span>\n\n                                  <\/a>\n                                                              <\/div>\n                              \n                              <div id=\"flush-collapse8858\" class=\"accordion-collapse collapse\" aria-labelledby=\"flush-heading8858\" data-bs-parent=\"#accordionFlushExample\">\n                                <ul class=\"accordion-body collapse_body_items pt-0\">\n                                  \n                                  <a href=\"https:\/\/novelis.io\/expertise\/#softwares\" class=\"py-2 px-4 mobile-nav-item \">Products<\/a>\n                                                                      <a href=\"https:\/\/novelis.io\/expertise\/#SmartRoby\u00ae\" class=\"py-2 px-4 mobile-nav-item \">SmartRoby: Your Automation Governance Platform<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/expertise\/#Novy%20POM\" class=\"py-2 px-4 mobile-nav-item \">Novy POM: Your Purchase & Order Management Platform<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/expertise\/#eShadow\" class=\"py-2 px-4 mobile-nav-item \">eShadow: Your Advanced Document Anonymization Solution<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/expertise\/#eSummarize\" class=\"py-2 px-4 mobile-nav-item \">eSummarize: Your Precision Summarization Solution<\/a>\n                                                                      \n                                <\/ul>\n                              <\/div>\n                                                          <\/div>\n\n                          \n\n                    \n                            <div class=\"accordion-item overflow-hidden\">\n                              <div class=\"accordion-header\" id=\"flush-heading629\">\n                                 \n                                  <a  class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-collapse629\" aria-expanded=\"false\" aria-controls=\"flush-collapse629\">\n                                  <span>Research Lab<\/span>\n\n                                  <\/a>\n                                                              <\/div>\n                              \n                              <div id=\"flush-collapse629\" class=\"accordion-collapse collapse\" aria-labelledby=\"flush-heading629\" data-bs-parent=\"#accordionFlushExample\">\n                                <ul class=\"accordion-body collapse_body_items pt-0\">\n                                  \n                                  <a href=\"https:\/\/novelis.io\/novelis-research-lab\/\" class=\"py-2 px-4 mobile-nav-item \">Novelis Research Lab<\/a>\n                                                                      <a href=\"\/novelis-research-lab#visions\" class=\"py-2 px-4 mobile-nav-item \">Vision<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/works\/\" class=\"py-2 px-4 mobile-nav-item \">Solutions<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/lab-news\/\" class=\"py-2 px-4 mobile-nav-item \">Lab News<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/scientific-publications\/\" class=\"py-2 px-4 mobile-nav-item \">Scientific publications<\/a>\n                                                                      \n                                <\/ul>\n                              <\/div>\n                                                          <\/div>\n\n                          \n\n                    \n                            <div class=\"accordion-item overflow-hidden\">\n                              <div class=\"accordion-header\" id=\"flush-heading1719\">\n                                 \n                                  <a  class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-collapse1719\" aria-expanded=\"false\" aria-controls=\"flush-collapse1719\">\n                                  <span>News<\/span>\n\n                                  <\/a>\n                                                              <\/div>\n                              \n                              <div id=\"flush-collapse1719\" class=\"accordion-collapse collapse\" aria-labelledby=\"flush-heading1719\" data-bs-parent=\"#accordionFlushExample\">\n                                <ul class=\"accordion-body collapse_body_items pt-0\">\n                                  \n                                  <a href=\"https:\/\/novelis.io\/our-news\/\" class=\"py-2 px-4 mobile-nav-item \">Our news<\/a>\n                                                                      <a href=\"https:\/\/novelis.io\/novelis-latest-news\/\" class=\"py-2 px-4 mobile-nav-item \">Novelis in the press<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/blog\/\" class=\"py-2 px-4 mobile-nav-item \">Our blog<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/events\/\" class=\"py-2 px-4 mobile-nav-item \">Events<\/a>\n                                                                      \n                                <\/ul>\n                              <\/div>\n                                                          <\/div>\n\n                          \n\n                    \n                            <div class=\"accordion-item overflow-hidden\">\n                              <div class=\"accordion-header\" id=\"flush-heading386\">\n                                 \n                                  <a  class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-collapse386\" aria-expanded=\"false\" aria-controls=\"flush-collapse386\">\n                                  <span>Our DNA<\/span>\n\n                                  <\/a>\n                                                              <\/div>\n                              \n                              <div id=\"flush-collapse386\" class=\"accordion-collapse collapse\" aria-labelledby=\"flush-heading386\" data-bs-parent=\"#accordionFlushExample\">\n                                <ul class=\"accordion-body collapse_body_items pt-0\">\n                                  \n                                  <a href=\"https:\/\/novelis.io\/dna\/\" class=\"py-2 px-4 mobile-nav-item \">Our corporate DNA<\/a>\n                                                                      <a href=\"https:\/\/novelis.io\/values\/\" class=\"py-2 px-4 mobile-nav-item \">Values<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/novelis-management\/\" class=\"py-2 px-4 mobile-nav-item \">Novelis Management<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/story\/\" class=\"py-2 px-4 mobile-nav-item \">Story<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/clients-testimonials\/\" class=\"py-2 px-4 mobile-nav-item \">Clients Testimonials<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/partners\/\" class=\"py-2 px-4 mobile-nav-item \">Partners<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/our-csr-strategy\/\" class=\"py-2 px-4 mobile-nav-item \">CSR Strategy<\/a>\n                                                                      \n                                <\/ul>\n                              <\/div>\n                                                          <\/div>\n\n                          \n\n                    \n                            <div class=\"accordion-item overflow-hidden\">\n                              <div class=\"accordion-header\" id=\"flush-heading582\">\n                                 \n                                  <a  class=\"accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-collapse582\" aria-expanded=\"false\" aria-controls=\"flush-collapse582\">\n                                  <span>Join us<\/span>\n\n                                  <\/a>\n                                                              <\/div>\n                              \n                              <div id=\"flush-collapse582\" class=\"accordion-collapse collapse\" aria-labelledby=\"flush-heading582\" data-bs-parent=\"#accordionFlushExample\">\n                                <ul class=\"accordion-body collapse_body_items pt-0\">\n                                  \n                                  <a href=\"https:\/\/novelis.io\/join-us\/\" class=\"py-2 px-4 mobile-nav-item \">Join our team<\/a>\n                                                                      <a href=\"https:\/\/novelis.io\/why-join-us\/\" class=\"py-2 px-4 mobile-nav-item \">Why join us<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/job-offers\/\" class=\"py-2 px-4 mobile-nav-item \">Open positions<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/spontaneous-application\/\" class=\"py-2 px-4 mobile-nav-item \">Submit your resume<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/professions\/\" class=\"py-2 px-4 mobile-nav-item \">Roles<\/a>\n                                                                        <a href=\"https:\/\/novelis.io\/frequently-asked-questions\/\" class=\"py-2 px-4 mobile-nav-item \">Frequently Asked Questions<\/a>\n                                                                      \n                                <\/ul>\n                              <\/div>\n                                                          <\/div>\n\n                          \n\n                    \n                            <div class=\"accordion-item overflow-hidden\">\n                              <div class=\"accordion-header\" id=\"flush-heading684\">\n                                                                  <a href=\"https:\/\/novelis.io\/contact-us\/\" class=\"accordion-button collapsed empty\" type=\"button\">\n                                  Contact\n                                  <\/a>\n                                                              <\/div>\n                                                          <\/div>\n\n                          \n\n                                        <div class=\"accordion-item overflow-hidden\">\n                      <div class=\"accordion-header accordion-button collapsed empty pb-0\" style=\"padding-top: 0.9rem;background: transparent;\">\n                        <li class=\"py-1 footer-lang\" id=\"wpml-lang-header-mobile\">\n                          <span><i class=\"bi bi-globe\"><\/i><\/span>\n                          \n<div class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-list-vertical\">\n\t<ul>\n\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item wpml-ls-item-legacy-list-vertical\">\n\t\t\t\t<a href=\"https:\/\/novelis.io\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/novelis.io\/wp-content\/uploads\/flags\/us.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-display\">Anglais<\/span><\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-fr wpml-ls-current-language wpml-ls-item-legacy-list-vertical\">\n\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/novelis.io\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\">Fran\u00e7ais<\/span><\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-de wpml-ls-last-item wpml-ls-item-legacy-list-vertical\">\n\t\t\t\t<a href=\"https:\/\/novelis.io\/de\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/novelis.io\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/de.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-display\">Allemand<\/span><\/a>\n\t\t\t<\/li>\n\t\t\n\t<\/ul>\n<\/div>\n                          \n                        <\/li>\n                        <script> wpmlGetChoosenLang(\"wpml-lang-header-mobile\") <\/script>\n                      <\/div>\n                    <\/div>\n                    \n                  <\/div>\n                  \n                  <ul class=\"navbar-nav ms-auto my-2 my-lg-0 d-none d-lg-flex\">\n                \n                    \n                          <li class=\"desktop-nav-link nav-item mt-1 mt-lg-0 mx-3 mx-lg-1 d-flex\"  desktop_submenu_button=\"1720\">\n                            <span   class=\"py-0 navitem-hover-only nav-link my-auto \" aria-current=\"page\" style='cursor:default;'>\n                              <a class=\"py-1\" href=\"https:\/\/novelis.io\/expertise\/\">Services<\/a>\n                              <i type=\"button\" class=\"bi bi-chevron-down\"><\/i>                            <\/span>\n                          <\/li>\n                        \n\n                    \n                          <li class=\"desktop-nav-link nav-item mt-1 mt-lg-0 mx-3 mx-lg-1 d-flex\"  desktop_submenu_button=\"8858\">\n                            <span   class=\"py-0 navitem-hover-only nav-link my-auto \" aria-current=\"page\" style='cursor:default;'>\n                              <a class=\"py-1\" href=\"https:\/\/novelis.io\/expertise\/#softwares\">Products<\/a>\n                              <i type=\"button\" class=\"bi bi-chevron-down\"><\/i>                            <\/span>\n                          <\/li>\n                        \n\n                    \n                          <li class=\"desktop-nav-link nav-item mt-1 mt-lg-0 mx-3 mx-lg-1 d-flex\"  desktop_submenu_button=\"629\">\n                            <span   class=\"py-0 navitem-hover-only nav-link my-auto \" aria-current=\"page\" style='cursor:default;'>\n                              <a class=\"py-1\" href=\"https:\/\/novelis.io\/novelis-research-lab\/\">Research Lab<\/a>\n                              <i type=\"button\" class=\"bi bi-chevron-down\"><\/i>                            <\/span>\n                          <\/li>\n                        \n\n                    \n                          <li class=\"desktop-nav-link nav-item mt-1 mt-lg-0 mx-3 mx-lg-1 d-flex\"  desktop_submenu_button=\"1719\">\n                            <span   class=\"py-0 navitem-hover-only nav-link my-auto \" aria-current=\"page\" style='cursor:default;'>\n                              <a class=\"py-1\" href=\"https:\/\/novelis.io\/our-news\/\">News<\/a>\n                              <i type=\"button\" class=\"bi bi-chevron-down\"><\/i>                            <\/span>\n                          <\/li>\n                        \n\n                    \n                          <li class=\"desktop-nav-link nav-item mt-1 mt-lg-0 mx-3 mx-lg-1 d-flex\"  desktop_submenu_button=\"386\">\n                            <span   class=\"py-0 navitem-hover-only nav-link my-auto \" aria-current=\"page\" style='cursor:default;'>\n                              <a class=\"py-1\" href=\"https:\/\/novelis.io\/dna\/\">Our DNA<\/a>\n                              <i type=\"button\" class=\"bi bi-chevron-down\"><\/i>                            <\/span>\n                          <\/li>\n                        \n\n                    \n                          <li class=\"desktop-nav-link nav-item mt-1 mt-lg-0 mx-3 mx-lg-1 d-flex\"  desktop_submenu_button=\"582\">\n                            <span   class=\"py-0 navitem-hover-only nav-link my-auto \" aria-current=\"page\" style='cursor:default;'>\n                              <a class=\"py-1\" href=\"https:\/\/novelis.io\/join-us\/\">Join us<\/a>\n                              <i type=\"button\" class=\"bi bi-chevron-down\"><\/i>                            <\/span>\n                          <\/li>\n                        \n\n                    \n                            <li class=\"d-none d-lg-block mx-1 ms-0\">\n                              <button type=\"button\" class=\"nav-item-button search_buttons btn h-100 navbar_transparent_button\">\n                                <i class=\"bi bi-search\"><\/i>\n                              <\/button>\n                            <\/li>\n    \n                          \n                            <li class=\"my-auto mt-1 mt-lg-0 mx-3 mx-lg-0\">\n                              <a class=\"btn btn-outline-secondary-light contact_button\" href=\"https:\/\/novelis.io\/contact-us\/\">Contact<\/a>\n                            <\/li>\n    \n                                                      \n                    \n                    \n                    <li class=\"mt-1 mt-lg-0\">\n                      <div class=\"btn-group h-100\">\n                        <button type=\"button\" class=\" nav-item-button btn navbar_transparent_button dropdown-toggle d-flex align-items-center mx-1\" data-bs-toggle=\"dropdown\" aria-expanded=\"false\" style=\"padding-right: 9px;padding-left: 13px;\">\n                        <span class=\"language_icon\" style='content : url(https:\/\/novelis.io\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.png)'><\/span>\n                        <\/button>\n                        <ul class=\"dropdown-menu dropdown-menu-end languages-nav-menu\" id=\"wpml-lang-header-desktop\">\n                          \n<div class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-list-vertical\">\n\t<ul>\n\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item wpml-ls-item-legacy-list-vertical\">\n\t\t\t\t<a href=\"https:\/\/novelis.io\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/novelis.io\/wp-content\/uploads\/flags\/us.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-display\">Anglais<\/span><\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-fr wpml-ls-current-language wpml-ls-item-legacy-list-vertical\">\n\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/novelis.io\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\">Fran\u00e7ais<\/span><\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-de wpml-ls-last-item wpml-ls-item-legacy-list-vertical\">\n\t\t\t\t<a href=\"https:\/\/novelis.io\/de\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/novelis.io\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/de.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-display\">Allemand<\/span><\/a>\n\t\t\t<\/li>\n\t\t\n\t<\/ul>\n<\/div>\n                          \n                        <\/ul>\n                        <script> wpmlGetChoosenLang(\"wpml-lang-header-desktop\") <\/script>\n                      <\/div>\n                    <\/li>\n                  <\/ul>\n                <\/div>\n              <\/div>\n            <\/nav>\n          <\/div>\n          <div class=\"position-relative d-none d-lg-block submenu_container\">\n                                      <nav class=\"submenu position-absolute w-100 overflow-hidden bg-light shadow-sm\" desktop_submenu_container=\"1720\">\n                              <div class=\"container py-2 d-flex flex-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t  \n                                <\/ul>\n\t\t\t\t\t\t\t\t  \n                                <ul class=\"row row-cols-6 flex-fill col-9\">\n                                  \n                                                                        <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertises\/automation-rpa-process-mining\/\">Intelligent Automation<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertises\/artificial-intelligence\/\">Artificial Intelligence and GenAI<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertises\/process-intelligence\/\">Process Intelligence<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertises\/innovative-architecture\/\">Innovative Architectures<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertises\/cybersecurity\/\">Cybersecurity<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/business-cases\/\">Business Cases<\/a><\/li>\n                                      \n                                <\/ul>\n                              <\/div>\n                            <\/nav>\n                        \n\n                                              <nav class=\"submenu position-absolute w-100 overflow-hidden bg-light shadow-sm\" desktop_submenu_container=\"8858\">\n                              <div class=\"container py-2 d-flex flex-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"row row-cols-6 flex-fill row col-3\">\n\t\t\t\t\t\t\t\t\t\t<li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertise\/#softwares\">Products<\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t  \n                                <\/ul>\n\t\t\t\t\t\t\t\t  \n                                <ul class=\"row row-cols-6 flex-fill col-9\">\n                                  \n                                                                        <li class=\"navitem-hover-only col-6 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertise\/#SmartRoby\u00ae\">SmartRoby: Your Automation Governance Platform<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-6 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertise\/#Novy%20POM\">Novy POM: Your Purchase & Order Management Platform<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-6 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertise\/#eShadow\">eShadow: Your Advanced Document Anonymization Solution<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-6 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/expertise\/#eSummarize\">eSummarize: Your Precision Summarization Solution<\/a><\/li>\n                                      \n                                <\/ul>\n                              <\/div>\n                            <\/nav>\n                        \n\n                                              <nav class=\"submenu position-absolute w-100 overflow-hidden bg-light shadow-sm\" desktop_submenu_container=\"629\">\n                              <div class=\"container py-2 d-flex flex-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t  \n                                <\/ul>\n\t\t\t\t\t\t\t\t  \n                                <ul class=\"row row-cols-6 flex-fill col-9\">\n                                  \n                                                                        <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"\/novelis-research-lab#visions\">Vision<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/works\/\">Solutions<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/lab-news\/\">Lab News<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/scientific-publications\/\">Scientific publications<\/a><\/li>\n                                      \n                                <\/ul>\n                              <\/div>\n                            <\/nav>\n                        \n\n                                              <nav class=\"submenu position-absolute w-100 overflow-hidden bg-light shadow-sm\" desktop_submenu_container=\"1719\">\n                              <div class=\"container py-2 d-flex flex-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t  \n                                <\/ul>\n\t\t\t\t\t\t\t\t  \n                                <ul class=\"row row-cols-6 flex-fill col-9\">\n                                  \n                                                                        <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/novelis-latest-news\/\">Novelis in the press<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/blog\/\">Our blog<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/events\/\">Events<\/a><\/li>\n                                      \n                                <\/ul>\n                              <\/div>\n                            <\/nav>\n                        \n\n                                              <nav class=\"submenu position-absolute w-100 overflow-hidden bg-light shadow-sm\" desktop_submenu_container=\"386\">\n                              <div class=\"container py-2 d-flex flex-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t  \n                                <\/ul>\n\t\t\t\t\t\t\t\t  \n                                <ul class=\"row row-cols-6 flex-fill col-9\">\n                                  \n                                                                        <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/values\/\">Values<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/novelis-management\/\">Novelis Management<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/story\/\">Story<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/clients-testimonials\/\">Clients Testimonials<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/partners\/\">Partners<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/our-csr-strategy\/\">CSR Strategy<\/a><\/li>\n                                      \n                                <\/ul>\n                              <\/div>\n                            <\/nav>\n                        \n\n                                              <nav class=\"submenu position-absolute w-100 overflow-hidden bg-light shadow-sm\" desktop_submenu_container=\"582\">\n                              <div class=\"container py-2 d-flex flex-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t  \n                                <\/ul>\n\t\t\t\t\t\t\t\t  \n                                <ul class=\"row row-cols-6 flex-fill col-9\">\n                                  \n                                                                        <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/why-join-us\/\">Why join us<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/job-offers\/\">Open positions<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/spontaneous-application\/\">Submit your resume<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/professions\/\">Roles<\/a><\/li>\n                                                                            <li class=\"navitem-hover-only col-3 nav-item \"><a class=\"nav-link submenu-item\" style=\"padding: 0.5rem 0rem;\" href=\"https:\/\/novelis.io\/frequently-asked-questions\/\">Frequently Asked Questions<\/a><\/li>\n                                      \n                                <\/ul>\n                              <\/div>\n                            <\/nav>\n                        \n\n                             <\/div> \n        <\/div>\n        <div id=\"section_tracker\" class=\"d-none d-md-flex section_tracker d-flex position-relative shadow-sm\" original_height=\"0\">\n          \n        <\/div>\n\n        <div id=\"search_container\" class=\"search_container search_container_hide mx-auto shadow-sm\">\n          <div id=\"search_bg_layer\" class=\"search_bg_layer_hidden position-absolute h-100 w-100\"><\/div>\n          <form action=\"\/\" method=\"GET\" id=\"search_box\" class=\"mx-auto search_box px-4 d-flex justify-content-start align-items-center bg-light position-relative\" >\n            <div class=\"me-4\"><i class=\"bi bi-search\"><\/i><\/div>\n            <input id=\"search_input\" autocomplete=\"off\" type=\"text\" name=\"s\" class=\"h-100 me-2 w-100\" style='all:unset;width: -webkit-fill-available; border: none' placeholder=\"Que cherchez-vous ?\">\n            <div id=\"empty_search_input\" style=\"font-size: 1.5rem;\" type=\"button\" class=\"close_button rounded-circle d-none d-lg-block\"><i class=\"bi bi-x d-flex\"><\/i><\/div>\n            <div id=\"close_search_mobile\" style=\"font-size: 1.5rem;\" type=\"button\" class=\"close_button rounded-circle d-block d-lg-none\"><i class=\"bi bi-x d-flex\"><\/i><\/div>\n          <\/form>\n          <div id=\"search_results\" style=\"max-height: 450px;overflow-y: scroll;\" class=\"mx-auto bg-light search_results box-shadow position-relative\">\n          <\/div>\n        <div>\n        <\/header>\n        <!-- <style>\n          \n          .category-search._0{\n            color: #313268;\n\n            background-color:  #ff007b80;\n          }\n          .category-search._1{\n            color:black;\n            background-color:  #06b4ff38;\n          }\n          .category-search._2{\n            color:black;\n            background-color:  #0083ff5c;\n          }\n          \n        <\/style> -->\n        <script>\n          sectionsTracker.sections_tracker(1);\n          navbar.navbar();\n          navbar.submenu_desktop();\n          video_max_height();\n\n\n          \/\/ search script\n          const results = document.getElementById(\"search_results\");\n          const searchInput = document.getElementById('search_input');\n\n          const lang = (document.querySelector(\"html\").getAttribute(\"lang\")).split(\"-\")[0];\n          const urlAddon = lang == 'en'?\"\":\"\/\"+lang;\n          let htmlresp;\n\n\n          const computedStyle = getComputedStyle(document.documentElement)\n          const colors = {\n                    primary :     computedStyle.getPropertyValue('--bs-primary'),\n                    secondary :     computedStyle.getPropertyValue('--bs-secondary'),\n                    accent :     computedStyle.getPropertyValue('--bs-secondary'),\n                    success : computedStyle.getPropertyValue('--bs-success'),\n                    warning : computedStyle.getPropertyValue('--bs-warning'),\n                  }\n          \/\/ const category\n          function debounce(func, timeout = 275){\n            let timer;\n            return (...args) => {\n              clearTimeout(timer);\n              timer = setTimeout(() => { func.apply(this, args); }, timeout);\n            };\n          }\n          async function saveInput(){\n            results.style.display = searchInput.value.length>0 ? \"block\":\"none\"\n            if(searchInput.value.trim().length==0)return \n\n            const query = await fetch(`https:\/\/novelis.io${urlAddon}\/wp-json\/custom\/v1\/search?s=${searchInput.value}`)\n            const respJSON = await query.json()\n\n            results.innerHTML=\"\"\n            respJSON.forEach(resp =>{\n                const urlDOM = document.createElement(\"div\")\n                urlDOM.classList = \"border-bottom p-4 py-2\"\n                urlDOM.style =\"cursor:pointer\"\n                urlDOM.role =\"button\"\n\n                \n\n                if(resp.type != \"\") htmlresp = `<div class=\"mb-1\"><span class=\"category-search\">${resp.type}<\/span><\/div>${resp.title}`\n                else htmlresp = resp.title;\n\n                urlDOM.innerHTML = htmlresp\n                urlDOM.addEventListener('click',()=>{\n                  window.location.href = resp.link;\n                })\n\n                results.appendChild(urlDOM)\n            })\n          }\n\n          const search = debounce(() => saveInput());\n          searchInput.addEventListener(\"input\",async ()=>{\n            search()\n          })\n        <\/script>\n        \n        <style>\n\t\t   html > label {\n\t\t    display: none;\n\t\t   }\n          .desktop-nav-link i{\n            background-color: #30316700;\n            padding: 4px 6px 3px 6px;\n            border-radius: 2px;\n            position: relative;\n            transition: background-color .5s ease;\n            bottom: 1px !important;\n\n            padding: 5px 6px;\n            border-radius: 40px;\n\n          }\n          .desktop-nav-link.active-arrow i,\n          .desktop-nav-link i:hover{\n            background-color: #3031671a\n\n          }\n\n          .desktop-nav-link i:before {\n              \n\n              transition: all 0.2s ease !important;\n              bottom: 0px;\n              position: relative  !important;\n          }\n\n          .desktop-nav-link.active-arrow i:before {\n              \n              \n              bottom: 1px;\n          }\n\n          .desktop-nav-link.active-arrow i{\n            bottom: 1px !important;\n          }\n\n          .navitem-hover-only.active a{\n            font-weight: 700;\n          }\n\n          .navitem-hover-only a:hover{\n            font-weight: 700 !important;\n          }\n\n         \n        <\/style>\n        \n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df73b9a elementor-widget elementor-widget-home_intro_slider\" data-id=\"df73b9a\" data-element_type=\"widget\" data-widget_type=\"home_intro_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n    <section class=\"text-light vh-100\" section_name=\"introduction\">\r\n        <div class=\"d-flex swiper w-100 \" style=\"position: relative;height: 100vh;\">\r\n\t\t\t\t\t<div class=\"swiper mySwiper w-100\" id=\"intro_slider_Swiper\">\r\n\t\t\t\t\t\t<div class=\"swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide grid_auto_1fr\">\r\n\t\t\t\t\t\t\t\t<div class=\"introduction_video_container vh-100 w-100 position-absolute top-0 bg-primary\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"position-absolute h-100 w-100 show-preload-img loaded-imgs\" style=\"z-index:-1;background-image:url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/08\/NOVELIS-2000-24-30x20.jpg)\" ><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<video class=\"introduction_video vh-100 w-100\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2023\/08\/idee-video-home-page-3-1-1-1.mp4\" muted=\"\" loop=\"\" autoplay=\"\"  playsinline><\/video>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"introduction_video_filter bg-primary vh-100 w-100 position-absolute top-0\" style=\"opacity : 75%\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"header_fake_height\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"container-md d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"intro-text\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"px-4\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pb-5\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pb-5 lh-base\">L'innovation au service de l'Efficacit\u00e9 Op\u00e9rationnelle<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"lh-base\">Notre mission est de r\u00e9volutionner l'efficacit\u00e9 op\u00e9rationnelle gr\u00e2ce \u00e0 l'innovation. En exploitant l'IA, l'automatisation et le Process Intelligence, nous transformons les op\u00e9rations, stimulons les performances et d\u00e9bloquons la croissance pour les entreprises du monde entier<\/h3>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pt-4\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/nos-expertises\" class=\"button-full-w-sm btn btn-secondary btn-lg text-uppercase\">En savoir plus<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"d-sm-flex swiper-pagination intro_slider_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 p-md-3 display-6\" style=\"position: absolute;top: 50%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\r\n\t\t\t\t\t\t<div class=\"d-sm-flex swiper-pagination intro_slider_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 p-md-3 display-6\" style=\"position: absolute;top: 50%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\r\n\t\t\t\t\t<\/div>\r\n        <\/div>\r\n    <\/section>\r\n  \t<script>\r\n\t\tintro_fake_header();\r\n    Home_intro_swiper()\r\n\t<\/script>\r\n\t\t\r\n\t<style>\r\n\t\t@media (max-width: 825px) {\r\n\t\t\t.intro-text h3{\r\n\t\t\t\tfont-size: 1.125rem;\r\n\t\t\t}\r\n\t\t}\r\n\t\t#intro_slider_Swiper .swiper-slide \r\n\t\t.swiper-wrapper.disabled {\r\n\t\ttransform: translate3d(0px, 0, 0) !important;\r\n\t\t}\r\n\t\t.swiper-pagination.disabled {\r\n\t\t\tdisplay: none !important;\r\n\t\t}\r\n\t<\/style>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbc490c elementor-widget elementor-widget-Expertises_swiper\" data-id=\"cbc490c\" data-element_type=\"widget\" data-widget_type=\"Expertises_swiper.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t <section class=\"bg-white grid_auto_1fr w-100\" section_name=\"Nos expertises\">\n    <div class=\"container\"> \n      <h2 class=\"px-4 px-sm-4 py-3 m-0 fw-bold section-title\">Nos <i>expertises<\/i><\/h2>\n    <\/div>\n\n    <div class=\"swiper w-100 h-100 nos_expertise_swiper\" id=\"nos_expertise_Swiper\"> \n      <div class=\"swiper-wrapper\">\n\n                    <div class=\"swiper-slide\">\n                              <div class=\"p-4 h-100 d-flex flex-column justify-content-between align-items-center text-center slider_container text-light position-relative overflow-hidden\">\n                  <div class=\"position-absolute top-0 left-0 h-100 w-100 bg-primary\" style=\"z-index: -2;\"><\/div>\n                  \n                  <div class=\"position-absolute top-0 left-0 h-100 w-100\">\n                    \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647203919_0\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/expertise-IA-600x432.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/expertise-IA-30x22.jpg\" class=\"loaded-imgs show-preload-img small\" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647203919_0\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                  <\/div>\n                  <div class=\"slides_color_effect w-100 h-100 position-absolute top-0\"><\/div>\n                  <div  class=\"d-flex flex-column slider_item_number position-relative\">\n                                          <img decoding=\"async\" style=\"filter: brightness(0) invert(1);height: 55px;\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/Automatisation-intelligente.svg\" class=\"m-auto mb-2\">\n                                        <h2 class=\"m-0 p-1\" style=\"width: min-content\">Automatisation Intelligente<\/h2>\n                  <\/div>\n                  <div class=\"py-2 px-0 slider_item_parag user-select-none position-relative\">Novelis d\u00e9mocratise l\u2019acc\u00e8s aux solutions d'Automatisation Intelligente. L\u2019automatisation par Robot est devenue un levier cl\u00e9 pour les entreprises souhaitant accroitre l'efficacit\u00e9 op\u00e9rationnelle de leur processus et gagner en comp\u00e9titivit\u00e9.<\/div>\n                  <a href=\"https:\/\/novelis.io\/fr\/expertises\/automatisation-intelligente\/\" class=\"p-1 link_container\">\n                    <div class=\"link link-light icon slider_item_link first-letter-capitalize\">En savoir plus<\/div>\n                  <\/a>\n                <\/div>\n                            <\/div>\n                          <div class=\"swiper-slide\">\n                              <div class=\"p-4 h-100 d-flex flex-column justify-content-between align-items-center text-center slider_container text-light position-relative overflow-hidden\">\n                  <div class=\"position-absolute top-0 left-0 h-100 w-100 bg-primary\" style=\"z-index: -2;\"><\/div>\n                  \n                  <div class=\"position-absolute top-0 left-0 h-100 w-100\">\n                    \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647203927_1\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/pexels-tara-winstead-8386440-1-600x400.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/pexels-tara-winstead-8386440-1-30x20.jpg\" class=\"loaded-imgs show-preload-img small\" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647203927_1\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                  <\/div>\n                  <div class=\"slides_color_effect w-100 h-100 position-absolute top-0\"><\/div>\n                  <div  class=\"d-flex flex-column slider_item_number position-relative\">\n                                          <img decoding=\"async\" style=\"filter: brightness(0) invert(1);height: 55px;\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/Intelligence-artificielle.svg\" class=\"m-auto mb-2\">\n                                        <h2 class=\"m-0 p-1\" style=\"width: min-content\">Intelligence Artificielle et IA G\u00e9n\u00e9rative<\/h2>\n                  <\/div>\n                  <div class=\"py-2 px-0 slider_item_parag user-select-none position-relative\">En tant que partenaire expert en mati\u00e8re d'efficacit\u00e9 op\u00e9rationnelle, nous proposons des solutions d'IA personnalis\u00e9es et s\u00e9curis\u00e9es. Notre Laboratoire R&D interne, compos\u00e9 d'une \u00e9quipe d'experts en IA, NLP et IA g\u00e9n\u00e9rative, vous guide de la conception au d\u00e9ploiement d'applications professionnelles de haute qualit\u00e9 ainsi que dans tous vos projets d\u2019IA.<\/div>\n                  <a href=\"https:\/\/novelis.io\/fr\/expertises\/intelligence-artificielle-ia-generative\/\" class=\"p-1 link_container\">\n                    <div class=\"link link-light icon slider_item_link first-letter-capitalize\">En savoir plus<\/div>\n                  <\/a>\n                <\/div>\n                            <\/div>\n                          <div class=\"swiper-slide\">\n                              <div class=\"p-4 h-100 d-flex flex-column justify-content-between align-items-center text-center slider_container text-light position-relative overflow-hidden\">\n                  <div class=\"position-absolute top-0 left-0 h-100 w-100 bg-primary\" style=\"z-index: -2;\"><\/div>\n                  \n                  <div class=\"position-absolute top-0 left-0 h-100 w-100\">\n                    \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647203936_2\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2022\/12\/MicrosoftTeams-image-34-600x400.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2022\/12\/MicrosoftTeams-image-34-30x20.jpg\" class=\"loaded-imgs show-preload-img small\" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647203936_2\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                  <\/div>\n                  <div class=\"slides_color_effect w-100 h-100 position-absolute top-0\"><\/div>\n                  <div  class=\"d-flex flex-column slider_item_number position-relative\">\n                                          <img decoding=\"async\" style=\"filter: brightness(0) invert(1);height: 55px;\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2022\/11\/Process-intelligence.svg\" class=\"m-auto mb-2\">\n                                        <h2 class=\"m-0 p-1\" style=\"width: min-content\">Process Intelligence<\/h2>\n                  <\/div>\n                  <div class=\"py-2 px-0 slider_item_parag user-select-none position-relative\">Novelis optimise les performances de votre entreprise en exploitant les donn\u00e9es historiques, factuelles et tangibles de vos SI gr\u00e2ce au Process Intelligence. Visualiser et comprendre le fonctionnement de vos processus est en effet indispensable pour d\u00e9cider des plans d\u2019actions \u00e0 mettre en \u0153uvre et pour prioriser vos projets d\u2019am\u00e9lioration d\u2019efficacit\u00e9 op\u00e9rationnelle.<\/div>\n                  <a href=\"https:\/\/novelis.io\/fr\/expertises\/process-intelligence\/\" class=\"p-1 link_container\">\n                    <div class=\"link link-light icon slider_item_link first-letter-capitalize\">En savoir plus<\/div>\n                  <\/a>\n                <\/div>\n                            <\/div>\n                          <div class=\"swiper-slide\">\n                              <div class=\"p-4 h-100 d-flex flex-column justify-content-between align-items-center text-center slider_container text-light position-relative overflow-hidden\">\n                  <div class=\"position-absolute top-0 left-0 h-100 w-100 bg-primary\" style=\"z-index: -2;\"><\/div>\n                  \n                  <div class=\"position-absolute top-0 left-0 h-100 w-100\">\n                    \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647203940_3\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/MicrosoftTeams-image-69-600x400.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/MicrosoftTeams-image-69-30x20.jpg\" class=\"loaded-imgs show-preload-img small\" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647203940_3\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                  <\/div>\n                  <div class=\"slides_color_effect w-100 h-100 position-absolute top-0\"><\/div>\n                  <div  class=\"d-flex flex-column slider_item_number position-relative\">\n                                          <img decoding=\"async\" style=\"filter: brightness(0) invert(1);height: 55px;\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/Architectures-innovantes.svg\" class=\"m-auto mb-2\">\n                                        <h2 class=\"m-0 p-1\" style=\"width: min-content\">Architectures Innovantes<\/h2>\n                  <\/div>\n                  <div class=\"py-2 px-0 slider_item_parag user-select-none position-relative\">Nous vous aidons \u00e0 d\u00e9finir la meilleure architecture technique et fonctionnelle et nous vous accompagnons dans l\u2019urbanisation de votre Syst\u00e8me d\u2019Information ainsi que sur la mise en place de l\u2019architecture associ\u00e9e.<\/div>\n                  <a href=\"https:\/\/novelis.io\/fr\/expertises\/architectures-innovantes\/\" class=\"p-1 link_container\">\n                    <div class=\"link link-light icon slider_item_link first-letter-capitalize\">En savoir plus<\/div>\n                  <\/a>\n                <\/div>\n                            <\/div>\n                          <div class=\"swiper-slide\">\n                              <div class=\"p-4 h-100 d-flex flex-column justify-content-between align-items-center text-center slider_container text-light position-relative overflow-hidden\">\n                  <div class=\"position-absolute top-0 left-0 h-100 w-100 bg-primary\" style=\"z-index: -2;\"><\/div>\n                  \n                  <div class=\"position-absolute top-0 left-0 h-100 w-100\">\n                    \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647203942_4\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/image-Site-31-600x338.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/image-Site-31-30x17.jpg\" class=\"loaded-imgs show-preload-img small\" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647203942_4\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                  <\/div>\n                  <div class=\"slides_color_effect w-100 h-100 position-absolute top-0\"><\/div>\n                  <div  class=\"d-flex flex-column slider_item_number position-relative\">\n                                          <img decoding=\"async\" style=\"filter: brightness(0) invert(1);height: 55px;\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/Cyber-security.svg\" class=\"m-auto mb-2\">\n                                        <h2 class=\"m-0 p-1\" style=\"width: min-content\">Cybers\u00e9curit\u00e9<\/h2>\n                  <\/div>\n                  <div class=\"py-2 px-0 slider_item_parag user-select-none position-relative\">Se pr\u00e9munir des risques cyber n\u2019est pas toujours synonyme de co\u00fbts importants et des actions simples peuvent d\u00e9j\u00e0 r\u00e9duire significativement votre exposition<\/div>\n                  <a href=\"https:\/\/novelis.io\/fr\/expertises\/cybersecurite\/\" class=\"p-1 link_container\">\n                    <div class=\"link link-light icon slider_item_link first-letter-capitalize\">En savoir plus<\/div>\n                  <\/a>\n                <\/div>\n                            <\/div>\n                  <\/div>\n\n      <div class=\"nos_expertise_swiper_button_prev nos_expertise_nav_slider start-0 p-3 display-6 h-100 top-0 position-absolute d-flex align-items-center justify-content-center text-light\" style=\"outline: 0;\"><i class=\"bi bi-chevron-left\"><\/i><\/div>\n      <div class=\"nos_expertise_swiper_button_next nos_expertise_nav_slider end-0 p-3 display-6 h-100 top-0 position-absolute d-flex align-items-center justify-content-center text-light\" style=\"outline: 0;\"><i class=\"bi bi-chevron-right\"><\/i><\/div>\n\n    <\/div>\n   \n\n  <\/section>\n<script>\n  nos_expertise_slider();\n<\/script>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-500c9e6 elementor-widget elementor-widget-Our_products\" data-id=\"500c9e6\" data-element_type=\"widget\" data-widget_type=\"Our_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t <section class=\"bg-white grid_auto_1fr w-100\" section_name=\"Produits\">\n    <div class=\"container\"> \n      <h2 class=\"px-4 px-sm-4 py-3 m-0 fw-bold section-title\">Nos <i>Produits<\/i><\/h2>\n    <\/div>\n\n    <div class=\"d-flex flex-column blog-body py-0\">\n              <div class=\"row row-cols-1 row-cols-md-2\">\n                                <div class=\"d-flex flex-column py-2 py-md-0 pb-md-3 \">\n                  <div\n                    class=\"flex-fill d-flex flex-column shadow overflow-hidden\"\n                  >\n                    <div class=\"p-4  d-flex flex-column align-items-start\" style=\"flex:1;\">\n                                              <img decoding=\"async\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/Smartroby.png\" style=\"height: 37px;\" class=\"mb-2\">\n                                            <div class=\"raleway text-accent mb-auto\"><!-- wp:heading {\"level\":4} -->\n<h4 class=\"wp-block-heading\">Your Automation Governance Platform<\/h4>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"className\":\"text-primary fw-normal\"} -->\n<p class=\"text-primary fw-normal\">SmartRoby est une solution qui soutient toutes les parties prenantes de la RPA dans leur&nbsp;parcours d'automatisation et rationaliser l'op\u00e9ration de RPA en facilitant l'\u00e9valuation de l'impact et la gestion de&nbsp;l'ex\u00e9cution des processus.&nbsp;\u200b<\/p>\n<!-- \/wp:paragraph --><\/div>\n                      <a href=\"https:\/\/smartroby.com\/\" type=\"button\" class=\"button-full-w-sm btn btn-sm btn-secondary mt-auto\" target=\"_blank\" rel=\"noopener\">En savoir plus<\/a\n                      >\n                    <\/div>\n\t\t\t\t\t                    <\/div>\n                <\/div>\n                                <div class=\"d-flex flex-column py-2 py-md-0 pb-md-3 \">\n                  <div\n                    class=\"flex-fill d-flex flex-column shadow overflow-hidden\"\n                  >\n                    <div class=\"p-4  d-flex flex-column align-items-start\" style=\"flex:1;\">\n                                              <img decoding=\"async\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/Logo-Novypom.png\" style=\"height: 37px;\" class=\"mb-2\">\n                                            <div class=\"raleway text-accent mb-auto\"><!-- wp:heading {\"level\":4} -->\n<h4 class=\"wp-block-heading\">Your Purchase &amp; Order Management Platform<\/h4>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"className\":\"text-primary fw-normal\"} -->\n<p class=\"text-primary fw-normal\">Novy POM est une solution d'entreprise qui permet le traitement intelligent et automatique des factures fournisseurs et des bons de commande clients, optimisant leur gestion tout au long de la cha\u00eene compl\u00e8te.<\/p>\n<!-- \/wp:paragraph --><\/div>\n                      <a href=\"https:\/\/novypom.com\/\" type=\"button\" class=\"button-full-w-sm btn btn-sm btn-secondary mt-auto\" target=\"_blank\" rel=\"noopener\">En savoir plus<\/a\n                      >\n                    <\/div>\n\t\t\t\t\t                    <\/div>\n                <\/div>\n                                <div class=\"d-flex flex-column py-2 py-md-0 pb-md-3 \">\n                  <div\n                    class=\"flex-fill d-flex flex-column shadow overflow-hidden\"\n                  >\n                    <div class=\"p-4  d-flex flex-column align-items-start\" style=\"flex:1;\">\n                       \n                        <h3 class=\"raleway text-primary pb-1\">eShadow<\/h3>\n                                            <div class=\"raleway text-accent mb-auto\"><!-- wp:paragraph -->\n<p><strong>Your Advanced Document Anonymization Solution\u00a0<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:html -->\n<p class=\"text-primary fw-normal\">eShadow est une solution avanc\u00e9e de pseudonymisation et d'anonymisation des documents con\u00e7ue pour prot\u00e9ger les donn\u00e9es sensibles. En utilisant des techniques sophistiqu\u00e9es combinant IA g\u00e9n\u00e9rative et IA symbolique, eShadow permet de s\u00e9curiser vos informations confidentielles, tout en pr\u00e9servant leur utilit\u00e9 pour l'analyse et le traitement des donn\u00e9es.\u00a0\u200b<\/p>\n<!-- \/wp:html --><\/div>\n                      <a href=\"https:\/\/novelis.io\/fr\/work\/eshadow-proteger-vos-donnees-avec-la-solution-de-pseudonymisation-et-danonymisation-des-documents-la-plus-avancee\/\" type=\"button\" class=\"button-full-w-sm btn btn-sm btn-secondary mt-auto\">En savoir plus<\/a\n                      >\n                    <\/div>\n\t\t\t\t\t                    <\/div>\n                <\/div>\n                                <div class=\"d-flex flex-column py-2 py-md-0 pb-md-3 \">\n                  <div\n                    class=\"flex-fill d-flex flex-column shadow overflow-hidden\"\n                  >\n                    <div class=\"p-4  d-flex flex-column align-items-start\" style=\"flex:1;\">\n                       \n                        <h3 class=\"raleway text-primary pb-1\">eSummarize<\/h3>\n                                            <div class=\"raleway text-accent mb-auto\"><!-- wp:paragraph -->\n<p><strong>Your Precision Summarization Solution<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:html -->\n<p class=\"text-primary fw-normal\">eSummarize est une solution innovante permettant de produire rapidement des r\u00e9sum\u00e9s pr\u00e9cis et concis \u00e0 partir de textes non structur\u00e9s et de longs documents. En utilisant des algorithmes d'IA g\u00e9n\u00e9rative, eSummarize extrait de vos documents toutes les informations essentielles pour vous fournir des r\u00e9sum\u00e9s de qualit\u00e9 en un seul clic.\u00a0\u200b<\/p>\n<!-- \/wp:html --><\/div>\n                      <a href=\"https:\/\/novelis.io\/fr\/work\/esummarize-le-moteur-de-resume-de-documents-a-base-de-lintelligence-artificielle\/\" type=\"button\" class=\"button-full-w-sm btn btn-sm btn-secondary mt-auto\">En savoir plus<\/a\n                      >\n                    <\/div>\n\t\t\t\t\t                    <\/div>\n                <\/div>\n                              <\/div>\n            <\/div>\n  <\/section>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d9eaf3 elementor-widget elementor-widget-Events_swiper\" data-id=\"3d9eaf3\" data-element_type=\"widget\" data-widget_type=\"Events_swiper.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t   <section class=\"bg-white grid_auto_1fr w-100 pb-2\" section_name=\"Ev\u00e8nements\">\n    <div class=\"container\">\n      <h2 class=\"px-4 px-sm-4 py-3 m-0 fw-bold section-title\">Nos  <i>Ev\u00e8nements<\/i><\/h2>\n    <\/div>\n\n    \n    <div class=\"container-fluid swiper w-100 p-0 event-swiper-container\" id=\"nos_evenements_Swiper\">\n      <div class=\"swiper-wrapper\" style=\"min-height: 600x;\">\n\n                            <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647203998_5\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/09\/Big-DATA-AI-4000-x-2500-px-1920x1200.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/09\/Big-DATA-AI-4000-x-2500-px-30x19.jpg\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647203998_5\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <a href=\"https:\/\/maps.app.goo.gl\/on2Mxb7B7TkA6bodA\" target=\"_blank\" class=\"link-secondary underline\" rel=\"noopener\">\n                                       \n                                        <i class=\"bi bi-geo-alt-fill me-1\"><\/i>\n                                                                            Paris Expo Porte de Versailles                                    <\/a>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>1 Oct , 2025<\/div>\n                                                                    <i class=\"bi bi-arrow-right-short px-1\"><\/i>\n                                  <div>2 Oct , 2025<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">Novelis participe \u00e0 Big Data &amp; AI Paris 2025\u00a0<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Rendez-vous les 1er et 2 octobre au Paris Expo Porte de Versailles pour l\u2019\u00e9v\u00e9nement incontournable d\u00e9di\u00e9 aux donn\u00e9es et \u00e0 l\u2019intelligence artificielle. Le mercredi 1er octobre \u00e0 12h30, notre CEO Mehdi Nafe et CTO Walid Dahhane pr\u00e9senteront \u00ab Comment l\u2019IA r\u00e9volutionne les interactions avec les syst\u00e8mes d\u2019information \u00bb.<\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/novelis-participe-a-big-data-ai-paris-2025\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/09\/LogoBDAIP-White-250x100.png\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                                    <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204004_6\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/05\/Banniere-teams-1200-x-628-px.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/05\/Banniere-teams-1200-x-628-px-30x16.png\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204004_6\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <a href=\"https:\/\/events.teams.microsoft.com\/event\/590521d8-9c18-44ce-9b4b-6b4d1b6631a3@04b313f5-b671-4bd9-a4ac-b7fc8910f7ab\" target=\"_blank\" class=\"link-secondary underline\" rel=\"noopener\">\n                                                                            Online                                    <\/a>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>25 Jun , 2025<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">[Webinar] Ce que vos processus vous cachent \u2013 mais que le Process Intelligence peut r\u00e9v\u00e9ler !\u00a0<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Vous cherchez \u00e0 am\u00e9liorer durablement la performance de vos processus m\u00e9tiers ? Dans notre prochain webinar, organis\u00e9 en partenariat avec SS&C Blue Prism, nous vous invitons \u00e0 d\u00e9couvrir comment le Process Intelligence permet de transformer en profondeur la performance op\u00e9rationnelle et d\u2019orienter efficacement vos projets d\u2019automatisation. <\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/webinar-ce-que-vos-processus-vous-cachent-mais-que-le-process-intelligence-peut-reveler\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/A-partner-of-SSC-blueprism-1-line-2col-logo-rgb-250x34.png\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                                    <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204007_7\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/04\/pic-1920x1280.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/04\/pic-30x20.jpg\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204007_7\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <div class='text-secondary'>\n                                       \n                                        <i class=\"bi bi-geo-alt-fill me-1\"><\/i>\n                                                                            Austin                                    <\/div>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>16 Apr , 2025<\/div>\n                                                                    <i class=\"bi bi-arrow-right-short px-1\"><\/i>\n                                  <div>17 Apr , 2025<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">Retour sur l\u2019\u00e9v\u00e9nement ABBYY \u2013 Talk : L&rsquo;avenir de l&rsquo;IA et de l&rsquo;Automatisation Intelligente<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Il y a quelques jours, notre partenaire ABBYY organisait un talk autour d\u2019un sujet strat\u00e9gique : l\u2019avenir de l\u2019IA et de l\u2019Automatisation Intelligente. Un moment d\u2019\u00e9change riche, o\u00f9 se sont r\u00e9unis des experts du secteur pour partager leur vision, leurs exp\u00e9riences concr\u00e8tes et les d\u00e9fis \u00e0 venir dans l\u2019adoption de ces technologies.<\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/retour-sur-levenement-abbyy-talk-lavenir-de-lia-et-de-lautomatisation-intelligente\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/ABBYY-e1639586562987-250x76.png\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                                    <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204009_8\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/11\/Webinar-ABBYY-with-Ina.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/11\/Webinar-ABBYY-with-Ina-30x17.jpg\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204009_8\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <div class='text-secondary'>\n                                                                            Online                                    <\/div>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>29 Oct , 2024<\/div>\n                                                                    <i class=\"bi bi-arrow-right-short px-1\"><\/i>\n                                  <div>29 Oct , 2024<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">Retour sur l&rsquo;\u00c9v\u00e9nement &#8211; Levelling Up From Process Mining to Process Intelligence<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Le 29 octobre, Ina Krebs a explor\u00e9 lors du SSON Summit comment le Process Intelligence transforme les donn\u00e9es de processus en d\u00e9cisions strat\u00e9giques. <\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/retour-sur-levenement-levelling-up-from-process-mining-to-process-intelligence\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/ABBYY-e1639586562987-250x76.png\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                                    <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204012_9\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/09\/Artificial-Intelligence-Expo.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/09\/Artificial-Intelligence-Expo-30x17.png\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204012_9\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <div class='text-secondary'>\n                                       \n                                        <i class=\"bi bi-geo-alt-fill me-1\"><\/i>\n                                                                            Bercy Lumi\u00e8re Building                                    <\/div>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>8 Oct , 2024<\/div>\n                                                                    <i class=\"bi bi-arrow-right-short px-1\"><\/i>\n                                  <div>8 Oct , 2024<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">Novelis participe au Salon de l&rsquo;Intelligence Artificielle du Minist\u00e8re de l&rsquo;Int\u00e9rieur<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Le mardi 8 octobre 2024, Novelis participera au Salon de l'Intelligence Artificielle de la Direction de la Transformation Num\u00e9rique du Minist\u00e8re de l'Int\u00e9rieur. L'occasion pour Novelis d'aborder le sujet de l'optimisation de la capitalisation et le partage gr\u00e2ce \u00e0 l'IA G\u00e9n\u00e9rative, pour rendre l'information accessible et instantan\u00e9e. <\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/novelis-participe-au-salon-de-lintelligence-artificielle\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                                    <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204014_10\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/09\/FR-1.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/09\/FR-1-30x16.png\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204014_10\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <div class='text-secondary'>\n                                                                            Online                                    <\/div>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>26 Sep , 2024<\/div>\n                                                                    <i class=\"bi bi-arrow-right-short px-1\"><\/i>\n                                  <div>26 Sep , 2024<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">[Webinar] \u00c9liminez les approximations de vos initiatives d&rsquo;automatisation intelligente avec l&rsquo;intelligence des processus\u00a0<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Rejoignez-nous le 26 septembre ! Rejoignez-nous pour une discussion captivante avec des leaders de l'industrie, dont Catherine Stewart, Pr\u00e9sidente des Am\u00e9riques chez Novelis. Ensemble, nous explorerons comment le \u00ab\u202fprocess mining\u202f\u00bb et le \u00ab\u202ftask mining\u202f\u00bb peuvent fournir les informations cruciales n\u00e9cessaires pour s'assurer que vous exploitez tout le potentiel de l'IA afin d'am\u00e9liorer l'efficacit\u00e9 op\u00e9rationnelle. Catherine partagera son expertise et ses exp\u00e9riences dans des initiatives d'automatisation intelligente qui g\u00e9n\u00e8rent un impact r\u00e9el.<\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/webinar-eliminez-les-approximations-de-vos-initiatives-dautomatisation-intelligente-avec-lintelligence-des-processus\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/ABBYY-e1639586562987-250x76.png\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                                    <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204016_11\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/06\/SSC-Blue-Prism-Live-London.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/06\/SSC-Blue-Prism-Live-London-30x17.png\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204016_11\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <a href=\"https:\/\/web.cvent.com\/event\/83c948a5-a1ff-48d5-bb92-cc22389aa389\/summary\" target=\"_blank\" class=\"link-secondary underline\" rel=\"noopener\">\n                                       \n                                        <i class=\"bi bi-geo-alt-fill me-1\"><\/i>\n                                                                            London                                    <\/a>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>11 Jun , 2024<\/div>\n                                                                    <i class=\"bi bi-arrow-right-short px-1\"><\/i>\n                                  <div>11 Jun , 2024<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">Novelis sponsorise le SS&amp;C Blue Prism Live \u00e0 Londres<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Le 11 juin, notre partenaire SS&C Blue Prism organise un \u00e9v\u00e9nement \u00e0 Londres centr\u00e9 sur l'IA et l'Automatisation Intelligente. Cet \u00e9v\u00e9nement est essentiel pour les professionnels de la technologie souhaitant ma\u00eetriser et mettre en \u0153uvre ces expertises dans leurs domaines. En tant que sponsor, Novelis est fier de faire partie de cette initiative, qui mettra en avant les derni\u00e8res strat\u00e9gies d'innovation.<\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/novelis-sponsorise-le-ssc-blue-prism-live-a-londres\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                                    <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204018_12\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/05\/SSC-Blue-Prism-Live-Frankfurt-1920x1080.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/05\/SSC-Blue-Prism-Live-Frankfurt-30x17.png\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204018_12\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <a href=\"https:\/\/web.cvent.com\/event\/0725f9f1-3934-4175-a4dc-d358c37f87fc\/summary\" target=\"_blank\" class=\"link-secondary underline\" rel=\"noopener\">\n                                       \n                                        <i class=\"bi bi-geo-alt-fill me-1\"><\/i>\n                                                                            Frankfurt                                    <\/a>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>14 May , 2024<\/div>\n                                                                    <i class=\"bi bi-arrow-right-short px-1\"><\/i>\n                                  <div>14 May , 2024<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">Novelis est sponsor de l&rsquo;\u00e9v\u00e9nement SS&#038;C Blue Prism Live \u00e0 Francfort<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Le 14 mai, un \u00e9v\u00e9nement ax\u00e9 sur l'IA et l'Automatisation sera organis\u00e9 \u00e0 Francfort par notre partenaire SS&C Blue Prism. Cet \u00e9v\u00e9nement est essentiel pour les professionnels de la technologie d\u00e9sireux de ma\u00eetriser et d'impl\u00e9menter l'Automatisation Intelligente et l'IA dans leurs domaines d'activit\u00e9. En tant que sponsor, Novelis est honor\u00e9 de participer \u00e0 cette initiative, qui mettra en lumi\u00e8re les strat\u00e9gies d'innovation les plus pertinentes.<\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/novelis-est-sponsor-de-levenement-ssc-blue-prism-live-a-francfort\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                                    <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204021_13\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-09-112228.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-09-112228-30x16.png\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204021_13\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <div class='text-secondary'>\n                                       \n                                        <i class=\"bi bi-geo-alt-fill me-1\"><\/i>\n                                                                            Le M\u00e9ridien Hotel, Fort Lauderdale, Florida                                    <\/div>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>1 May , 2024<\/div>\n                                                                    <i class=\"bi bi-arrow-right-short px-1\"><\/i>\n                                  <div>2 May , 2024<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">Novelis est sponsor du Chief AI Officer USA Exchange en Floride<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Les 1er et 2 mai, Novelis sponsorise le Chief AI Officer USA Exchange \u00e0 Fort Lauderdale, en Floride !\r\nCet \u00e9v\u00e9nement joue un r\u00f4le crucial en aidant les entreprises \u00e0 tirer parti des avantages de l'IA et \u00e0 naviguer prudemment \u00e0 travers ses d\u00e9fis \u00e9thiques et ses probl\u00e9matiques de confidentialit\u00e9 dans un paysage en \u00e9volution rapide.\r\nRejoignez nos experts Catherine Stewart, Pr\u00e9sidente et Directrice G\u00e9n\u00e9rale pour les Am\u00e9riques, et Paul Branson, Directeur des Solutions Techniques, qui seront pr\u00e9sents !<\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/novelis-est-sponsor-du-chief-ai-officer-usa-exchange-en-floride\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/04\/Chief-AI-Officer-USA-250x113.png\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                                    <style>\n                      .event-swiper-container .swiper-button-disabled {\n                        display: none !important;\n                      }\n                    <\/style>\n                    <div class=\"swiper-slide position-relative\">\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n                      <div class=\"d-sm-flex nos_evenements_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-1 display-6 d-block d-lg-none\" style=\"position: absolute;top: 55%;z-index: 1;translate: 0% -50%;right:0;\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n                      <div class=\"container-fluid h-100\">\n                        <div class=\"row h-100\">\n                          \n                          <div class=\"col-12 col-lg-6 p-0 overflow-hidden position-relative\" style=\"min-height: 20vh\">\n\n                            <div class=\"nos_evenements_background_img w-100 h-100\">\n                              \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204024_14\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/04\/BLOG-1200-\u00d7-628-px-2.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/04\/BLOG-1200-\u00d7-628-px-2-30x16.png\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204024_14\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t                            <\/div>\n                            \n                            <div class=\"background_filter_gradient h-100 w-100 position-relative \"><\/div>\n                            <div class=\"position-absolute top-50 start-0 translate-middle-y ps-5\">\n                              <button type=\"button\" style=\"box-shadow: 0 3px 20px 3px #00000033;background-color: #e6e3e6;\" class=\"d-none d-lg-block lateral-event-swiper-button px-2 nos_evenements_swiper_button_prev square ms-auto me-2 btn btn-outline-dark show_bg rounded-3\">\n                                <i class=\"bi bi-arrow-left d-flex\"><\/i>\n                              <\/button>\n                            <\/div>\n                          <\/div>\n                          <div class=\"col-12 col-lg-6 px-5 py-4 events_bg d-flex flex-row\">\n                            <div class=\"d-flex flex-column justify-content-between h-100 flex-fill\">\n                              <div class=\"d-flex flex-column flex-fill\">\n                                \n                                <div class=\"text-secondary fw-bold d-flex justify-content-between py-1 flex-wrap\" >\n                                  <div class=\"flex-grow-1 pe-1\">\n                                                                        <a href=\"https:\/\/web.cvent.com\/event\/2cf1ebc5-fb06-4160-bcc9-2df320af00ef\/summary?Refid=LP\" target=\"_blank\" class=\"link-secondary underline\" rel=\"noopener\">\n                                       \n                                        <i class=\"bi bi-geo-alt-fill me-1\"><\/i>\n                                                                            New-York                                    <\/a>\n                                                                      <\/div>\n                                  <div class=\"d-flex\">\n                                                                    <div>30 Apr , 2024<\/div>\n                                                                    <i class=\"bi bi-arrow-right-short px-1\"><\/i>\n                                  <div>30 Apr , 2024<\/div>\n                                                                    <\/div>\n                                <\/div>\n                                <div class=\"fw-bold py-1\">Novelis, sponsor de l&rsquo;\u00e9v\u00e9nement SS&#038;C Blue Prism Live \u00e0 New York<\/div>\n                                <div class=\"flex-fill d-flex flex-row\">\n                                  <div class=\"py-3 flex-fill pe-2\">Le 30 avril, notre partenaire SS&C Blue Prism Live organise un \u00e9v\u00e9nement \u00e0 New York sur le th\u00e8me de l'IA et de l'Automatisation. C'est un \u00e9v\u00e9nement cl\u00e9 pour les professionnels de la technologie d\u00e9sireux de comprendre et d\u2019appliquer les principes de l\u2019automatisation intelligente et de l\u2019intelligence artificielle dans leurs domaines d\u2019activit\u00e9. Novelis, en tant que sponsor, est fier de s\u2019associer \u00e0 cet \u00e9v\u00e9nement qui promet de mettre en lumi\u00e8re les strat\u00e9gies d\u2019innovation les plus pertinentes de notre \u00e9poque.<\/div>\n                                  <div class=\"d-none d-lg-block m-auto\">\n                                    <button type=\"button\" style=\"margin-top: 19px;\" class=\"lateral-event-swiper-button  px-2 nos_evenements_swiper_button_next square ms-auto  btn btn-outline-dark show_bg rounded-3\">\n                                      <i class=\"bi bi-arrow-right d-flex\"><\/i>\n                                    <\/button>\n                                  <\/div>\n                                <\/div>\n                                <div class=\"d-flex justify-content-end\">\n                                  <a href=\"https:\/\/novelis.io\/fr\/events\/ss-c-blue-prism-live-ny-automatisation-ia-30-avril\/\" class=\"link-secondary icon first-letter-capitalize\">\n                                    En savoir plus                                  <\/a>\n                                <\/div>\n                              <\/div>\n                              <div class=\"row align-items-end pt-3\">\n                                <div class=\"col my-auto\">\n                                  <div class=\" buh-100 w-100 d-flex justify-content-end\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"event_company_logo\" src=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/04\/BLOG-1200-\u00d7-628-px-2-250x131.png\">\n                                  <\/div>\n                                <\/div>\n                              <\/div>\n                            <\/div>\n                          <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n\n                \n\n\n        \n        \n        \n      <\/div>\n      \n      \n\n    <\/div>\n   \n       \n  <\/section>\n  <style>\n    .lateral-event-swiper-button:disabled{\n      display: none !important;\n    }\n  <\/style>\n  <script>\n  \tnos_evenements_Swiper();\n  <\/script>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30da5c3 elementor-widget elementor-widget-Latest_news\" data-id=\"30da5c3\" data-element_type=\"widget\" data-widget_type=\"Latest_news.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- derniers actualites -->\n\t\t<style>\n\t\t\t*{\n\t\t\t\tfont-style: normal;\n\t\t\t}\n\t\t<\/style>\n\t\t<section class=\"d-flex flex-column pt-0 pb-5\" section_name=\"Nos derni\u00e8res actualit\u00e9s\">\n\t\t\t\t\t\t<div class=\"container\"> \n\t\t\t\t<h2 class=\"px-4 px-sm-4 py-3 m-0 fw-bold section-title\">Nos derni\u00e8res <i>actualit\u00e9s<\/i><\/h2>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"d-flex flex-column blog-body py-0\">\n\n\t\t\t\t<style>\n\t\t\t\t\t@media (min-width: 1150px) {\n\t\t\t\t\t\t.vertical-on-sidebar{\n\t\t\t\t\t\t\tflex-direction : column;\n\t\t\t\t\t\t}\n\t\t\t\t\t\t.vertical-on-sidebar > *{\n\t\t\t\t\t\t\twidth: 100%;\n\t\t\t\t\t\t}\n\t\t\t\t\t}\n\t\t\t\t<\/style>\n\n\t\t\t\t<div class=\"row row-cols-1 row-cols-md-3 \">\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"d-flex flex-column py-2 py-md-0\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/news\/livre-blanc-de-la-rpa-a-lia-agentique-gouvernee\/\" class=\"presse-en-parle-image col-12 shadow-sm-light\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204036_15\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2026\/05\/2-600x314.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2026\/05\/2-30x16.png\" class=\"loaded-imgs show-preload-img small\" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204036_15\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t<div class=\"flex-fill d-flex flex-column ps-0 pt-2\">\n\t\t\t\t\t\t\t\t<div style=\"min-height: 23px;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/news\/livre-blanc-de-la-rpa-a-lia-agentique-gouvernee\/\" class=\"text-black \"><h4 class=\"raleway\">[Livre Blanc]\u00a0De la RPA\u00a0\u00e0 l\u2019IA agentique gouvern\u00e9e\u00a0<\/h4><\/a>\n\t\t\t\t\t\t\t\t<div class=\"mt-auto d-flex flex-row align-items-center\">\n\t\t\t\t\t\t\t\t\t<p class='bi bi-calendar me-1  m-0 ps-0 text-grey-light-3'><\/p>\n\t\t\t\t\t\t\t\t\t<p class=\"m-0 me-2 text-grey-light-3 font-weight-bold \">\n\t\t\t\t\t\t\t\t\t\t12 Mai , 2026\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"d-flex flex-column py-2 py-md-0\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/news\/tournee-pfe-2026-retour-sur-une-edition-riche-en-echanges-et-en-rencontres\/\" class=\"presse-en-parle-image col-12 shadow-sm-light\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204038_16\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/12\/image-Site-6-600x338.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/12\/image-Site-6-30x17.jpg\" class=\"loaded-imgs show-preload-img small\" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204038_16\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t<div class=\"flex-fill d-flex flex-column ps-0 pt-2\">\n\t\t\t\t\t\t\t\t<div style=\"min-height: 23px;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/news\/tournee-pfe-2026-retour-sur-une-edition-riche-en-echanges-et-en-rencontres\/\" class=\"text-black \"><h4 class=\"raleway\">Tourn\u00e9e PFE\u00a02026 : retour sur une \u00e9dition riche en \u00e9changes et en rencontres\u00a0<\/h4><\/a>\n\t\t\t\t\t\t\t\t<div class=\"mt-auto d-flex flex-row align-items-center\">\n\t\t\t\t\t\t\t\t\t<p class='bi bi-calendar me-1  m-0 ps-0 text-grey-light-3'><\/p>\n\t\t\t\t\t\t\t\t\t<p class=\"m-0 me-2 text-grey-light-3 font-weight-bold \">\n\t\t\t\t\t\t\t\t\t\t9 D\u00e9c , 2025\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"d-flex flex-column py-2 py-md-0\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/news\/novelis-participe-au-duoday-2025\/\" class=\"presse-en-parle-image col-12 shadow-sm-light\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204039_17\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/11\/image-Site-3-600x338.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/11\/image-Site-3-30x17.jpg\" class=\"loaded-imgs show-preload-img small\" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204039_17\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t<div class=\"flex-fill d-flex flex-column ps-0 pt-2\">\n\t\t\t\t\t\t\t\t<div style=\"min-height: 23px;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/news\/novelis-participe-au-duoday-2025\/\" class=\"text-black \"><h4 class=\"raleway\">Novelis participe au DuoDay 2025\u00a0<\/h4><\/a>\n\t\t\t\t\t\t\t\t<div class=\"mt-auto d-flex flex-row align-items-center\">\n\t\t\t\t\t\t\t\t\t<p class='bi bi-calendar me-1  m-0 ps-0 text-grey-light-3'><\/p>\n\t\t\t\t\t\t\t\t\t<p class=\"m-0 me-2 text-grey-light-3 font-weight-bold \">\n\t\t\t\t\t\t\t\t\t\t24 Nov , 2025\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/blog\/\" type=\"button\" class=\"button-full-w-sm btn btn-outline-secondary mt-5 align-self-center\">Afficher tout<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e793acf elementor-widget elementor-widget-Expertise_block_text_with_image\" data-id=\"e793acf\" data-element_type=\"widget\" data-widget_type=\"Expertise_block_text_with_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"w-100 pb-5\" id=\"visions\"  section_name=\"Certifications\">\n\t\t\t\t\t\t\t\t<div class=\"position-relative\">\n\t\t\t\t\t\t<div class=\"vision_bg position-absolute h-100 w-50 bg-primary top-0 d-none d-md-block\"><\/div>\n\n\t\t\t\t\t\t<div class=\"vision-container container-xl position-relative my-auto\">\n\t\t\t\t\t\t\t\t<div class=\"vision_bg bg-primary position-absolute top-0\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t\t.ecpertise_new_container{\n\t\t\t\t\t\t\t\t\t\tdisplay: grid;\n\t\t\t\t\t\t\t\t\t\tgrid-template-columns: 3fr 4fr;\n\t\t\t\t\t\t\t\t\t\twidth: 100%;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t@media (max-width: 767.98px){\n\t\t\t\t\t\t\t\t\t.ecpertise_new_container {\n\t\t\t\t\t\t\t\t\t\t\tgrid-template-columns: 100%;\n\t\t\t\t\t\t\t\t\t\t\twidth: 80%;\n\t\t\t\t\t\t\t\t\t}}\n\t\t\t\t\t\t\t\t\t.logos-container{\n\t\t\t\t\t\t\t\t\t\tdisplay: flex;\n\t\t\t\t\t\t\t\t\t\tfilter: drop-shadow(0px 3px 7px #0000001a);\n\t\t\t\t\t\t\t\t\t\twidth: 100%;\n\t\t\t\t\t\t\t\t\t\tmargin: 28px;\n\t\t\t\t\t\t\t\t\t\theight: 108px;\n\t\t\t\t\t\t\t\t\t\tjustify-content: space-between;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t@media (max-width: 1105px){\n\t\t\t\t\t\t\t\t\t.logos-container {\n\t\t\t\t\t\t\t\t\t\theight: 88px;\n\t\t\t\t\t\t\t\t\t}}\n\n\t\t\t\t\t\t\t\t\t@media (max-width: 767.98px){\n\t\t\t\t\t\t\t\t\t.logos-container {\n\t\t\t\t\t\t\t\t\t\theight: 83px;\n\t\t\t\t\t\t\t\t\t}}\n\t\t\t\t\t\t\t\t\t@media (max-width: 572px){\n\t\t\t\t\t\t\t\t\t.logos-container {\n\t\t\t\t\t\t\t\t\t\theight: auto;\n\t\t\t\t\t\t\t\t\t\tflex-direction: column;\n\t\t\t\t\t\t\t\t\t\talign-items: center;\n\t\t\t\t\t\t\t\t\t\tgap: 27px;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t.logos-container img{\n\t\t\t\t\t\t\t\t\t\theight: 88px !important;\n\t\t\t\t\t\t\t\t\t}}\n\n\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<div class=\"ecpertise_new_container m-auto py-4\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"pb-3 pb-md-0 px-0 ps-md-2 pe-md-5 text-light position-relative d-flex flex-column  justify-content-around\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/expertises\/cybersecurity\/\" class=\"text-light\"><h2 class=\"mb-4\">Certifi\u00e9s ISO 27001 <\/h2><\/a> \n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"mb-3\"><p>La <a class=\"link-light\" href=\"https:\/\/novelis.io\/fr\/in_the_press\/novelis-obtient-la-certification-afaq-iso-iec-27001\/\">certification AFAQ ISO\/IEC 27001<\/a> d\u00e9montre que nous avons mis en place un Syst\u00e8me de management de la s\u00e9curit\u00e9 de l\u2019information (SMSI) efficace construit sur la base de la norme internationale de r\u00e9f\u00e9rence, l\u2019ISO 27001.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"position-relative first-letter-capitalize\"><a href=\"https:\/\/novelis.io\/expertises\/cybersecurity\/\" class=\"link-light icon\">En savoir plus<\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t \n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/novelis.io\/expertises\/cybersecurity\/\" class=\"vision-img bg-light position-relative my-auto d-flex shadow overflow-hidden\">\n\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204065_18\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/image-Site-31-600x338.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/11\/image-Site-31-30x17.jpg\" class=\"loaded-imgs show-preload-img small\" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204065_18\",\"16\/9\")<\/script>\n\t\t\t<\/div>\n\t\t \n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n    \n\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8f6656 elementor-widget elementor-widget-Join_us\" data-id=\"c8f6656\" data-element_type=\"widget\" data-widget_type=\"Join_us.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t \n<section id=\"nous_rejoindre\" section_name=\"Rejoignez notre \u00e9quipe !\" style=\"overflow: hidden;position: sticky;top:0\" class=\"pb-5\">\n    <!-- <div class=\"container\">\n      <h1 class=\"p-4 m-0 fw-bold\">Nous <span class=\"text-secondary\">rejoindre<\/span><\/h1>\n    <\/div> -->\n    <div id=\"content_test\" class=\"position-relative\" style='min-height: inherit;\n        width: 100%;\n        transition:all 0.4s ease;\n        top:0;'>\n\t\t<div id=\"nous_rejoindre_img\" class=\"nous_rejoindre_img h-100 w-100 position-absolute top-0\">\n\t\t\t\t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204067_19\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/05\/group-photo-symposium-morocco.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/05\/group-photo-symposium-morocco-30x17.png\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204067_19\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t \n\t  <div id=\"nous_rejoindre_color_effect\" class=\"nous_rejoindre_color_effect bg-primaryDark w-100 h-100 position-absolute top-0 bg-primary\" ><\/div>\n     <div class=\"grid_auto_1fr h-100\" style=\"min-height: inherit;padding:3.5rem;padding-right: 0px;padding-left: 0px;\">\n\t  <div style=\"height:0px\"><\/div>\n\t  <div class=\"container text-light d-flex align-items-center\">\n        <div id=\"nous_rejoindre_content\" class=\"nous_rejoindre_content row p-4 flex-lg-row-reverse justify-content-center\">\n          \n          <div class=\"col-12 col-xl-6 d-flex align-items-center justify-content-center\" style=\"max-width: 650px;\">\n            <div class=\"nous_rejoindre_video_container w-100\">\n              <div class=\"plyr__video-embed youtube_video\" id=\"player_nous_rejoindre\">\n                <iframe  \n                  src=\"https:\/\/youtu.be\/60VKSUmBqxs\"\n                  allowfullscreen\n                  allowtransparency\n                  allow=\"autoplay\"\n\n\n                ><\/iframe>\n              <\/div>\n            <\/div>\n            \n          <\/div>\n\n          <div class=\"col-12 col-lg-10 col-xl-6 d-flex flex-column\">\n            <h2 class=\"my-3 my-xl-3 mt-xl-0 fw-bold heading_text_shadow\">Rejoignez notre \u00e9quipe !<\/h2>\n            <div class=\"my-2 my-xl-4 heading_text_shadow flex-fill\">Rejoindre Novelis, c\u2019est faire partie d\u2019un projet collectif d\u2019entreprise, travailler sur des technos \u00e9mergeantes et avoir un impact sur le monde technologique de demain.\n\n#WeImpactTechnologies <\/div>\n            <div class=\"mb-2\">\n\t\t\t \n              <a href=\"https:\/\/novelis.io\/fr\/offres-demploi\/\" type=\"button\" class=\"button-full-w-sm btn btn-outline-light me-2 mt-2 mt-xl-3\">Nos offres d\u2019emploi<\/a>\n             \n\t\t\t \n              <a href=\"https:\/\/novelis.io\/fr\/candidature-spontanee\/\" type=\"button\" class=\"button-full-w-sm btn btn-secondary  mt-2 mt-xl-3\">Postuler\u00a0<\/a>\n             \n\t\t\t<\/div>\n          <\/div>\n          \n        <\/div>\n      <\/div>\n\t <\/div> \n\n    <\/div>\n\t<div id=\"mouse_scroll\" class=\"parallax_scroll_indicator\">\n\t\t<i class=\"bi bi-mouse-fill parallax_scroll_indicator_mouse\" style=\"font-size:2rem\"><\/i>\n\t\t<i class=\"bi bi-circle-fill parallax_scroll_indicator_touch\"><\/i>\n\t<\/div>\n\n\t<style>\n\n\t\t.parallax_scroll_indicator_mouse,\n\t\t.parallax_scroll_indicator_touch{\n\t\t\tdisplay: none;\n\t\t}\n\t\n\t\t.mouse .parallax_scroll_indicator_mouse{\n\t\t\tdisplay: block;\n\t\t}\n\t\t.touch .parallax_scroll_indicator_touch{\n\t\t\tdisplay: block;\n\t\t}\n\n\t\t@keyframes scroll_mouse {\n\t\t\t0% {\n\t\t\t\ttransform: translateX(-50%) translateY(0%);\n\t\t\t}\n\t\t\t30% {\n\t\t\t\ttransform: translateX(-50%) translateY(50%);\n\t\t\t}\n\t\t\t50% {\n\t\t\t\ttransform: translateX(-50%) translateY(0%);\n\t\t\t}\n\t\t\t100% {\n\t\t\t\ttransform: translateX(-50%) translateY(0%);\n\t\t\t}\n\t\t}\n\n\t\t.parallax_scroll_indicator{\n\t\t\tcolor: white;\n\t\t\tposition: absolute;\n\t\t\tz-index: 30;\n\t\t\ttext-shadow: 0px 0px 4px black;\n\t\t\tbottom: 55px;\n\t\t\tleft: 50%;\n\t\t\ttransform: translateX(-50%);\n\t\t\tanimation: scroll_mouse 3s infinite;\n\t\t\tfilter: drop-shadow(0px 0px 1px black);\n\t\t\topacity: 0%;\n\t\t\ttransition: opacity 0.3s ease  ;\n\t\t}\n\n\t\t.show_scroll_mouse{\n\t\t\topacity:50%;\n\t\t}\n\n\t\t\n\t\t.parallax{\n\t\t\theight:100%;\n\t\t\twidth: 100%;\n\t\t\tposition:absolute;\n\t\t\ttop:0;\n\t\t\tleft:0;\n\t\t\tpointer-events: none;\n\t\t}\n\t\t.svg_N_logo{\n\t\t\tmin-width: 100%;\n\t\t\tmin-height: 100%;\n\t\t\theight: intrinsic;\n\t\t\tposition: relative;\n\t\t\tleft: 50%;\n\t\t\ttop:50%;\n\t\t\ttransform : translate(-50%,-50%);\n\t\t\t\/* transition: all 0.1s cubic-bezier(0.12, 0.46, 0.54, 1.01); *\/\n\t\t\t\/* will-change: transform; *\/\n\t\t}\n\t\t\n\t\t.nous_rejoindre_content{\n\t\t\topacity:100%;\n\t\t\ttransition:all 0.4s ease;\n\t\t}\n\t\t.nous_rejoindre_blur_filter{\n\t\t\t\/* backdrop-filter: blur(20px) brightness(1.8);\n\t\t\tbox-shadow: 0px 3px 5px -1px rgb(0 0 0 \/ 20%), 0px 6px 10px 0px rgb(0 0 0 \/ 14%), 0px 1px 24px 0px rgb(0 0 0 \/ 44%); *\/\n\t\t}\n\t\t.show_magic{\n\t\t\topacity:100%;\n\t\t}\n\n\t\t\n\n\t\t@media (max-width: 1200px) {\n\t\t\t.nous_rejoindre_content{\n\t\t\t\theight:100%;\n\t\t\t\tbackdrop-filter: none;\n\t\t\t\tbox-shadow: none;\n\t\t\t}\n\n\t\t}\n\t\t.nous_rejoindre_img{\n    \n\t\t\ttransition: transform 0.2s cubic-bezier(0, 0.89, 0.58, 1) ,filter .3s linear !important;\n\t\n\t\t\twill-change: transform;\n\t\t}\n\t\n\t\t.nous_rejoindre_color_effect{\n\t\t\topacity: 55%;\n\t\t\ttransition: opacity 0.3s ease;\n\t\t}\n\t\t.higher_filter_opacity{\n\t\t\topacity: 70%;\n\t\t}\n\n\t\t.img_blur{\n\t\t\tfilter: blur(50px);\n\t\t}\n\t\t\n\n\t<\/style>\n\n  <\/section>\n  <script>\n\t\/\/nous_rejoindre_fake_height();\n  \tplayer_nous_rejoindre();\n  <\/script>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d77ec8 elementor-widget elementor-widget-Clients_swiper\" data-id=\"4d77ec8\" data-element_type=\"widget\" data-widget_type=\"Clients_swiper.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n    <section class=\"bg-primary\" section_name=\"Nos clients\">\n        <div class=\"container d-flex\">\n            <h2 class=\"px-1 px-sm-4 py-4 pb-2 py-md-4 mx-auto m-0 fw-bold text-light text-center\">Ils nous font confiance<\/h2>\n        <\/div>\n\n        <div class=\"d-flex container-lg pb-5\">\n            <div class=\"d-none d-sm-flex partenaires_swiper_button_prev partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-3 display-6\"><i class=\"bi bi-chevron-left d-flex\"><\/i><\/div>\n\n            <div class=\"swiper\" id=\"partenaires_Swiper\">\n                <div class=\"swiper-wrapper\" >\n                                            <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/apicil-250x79.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2023\/12\/logo-Ramsay-Sante-246x250.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2023\/08\/telechargement-removebg-preview-1-250x67.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2023\/05\/LOGO_NOIR_RVB-removebg-preview-250x155.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/10\/telechargement__8_-removebg-preview-250x77.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/contaxium-250x33.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/Groupe-Soufflet-ART-logo-2019-250x71.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/1200px-CMB_MONACO_SVG.svg_-e1645174241842-250x141.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/admin-ajax-250x27.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/conseil-detat-250x195-removebg-preview.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/irsn-250x173.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/ME-GROUP-250x239.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/10\/telechargement__8_-removebg-preview-250x77.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/iquera-250x107.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/accor-e1644850930118-250x204.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/helpline-1-removebg-preview-e1645174052835-250x49.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/carglass-250x67.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/desigual-scaled-removebg-preview-e1645174320764-250x63.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/engue-e1645174390724-250x101.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/grand-frais-250x250.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/nexans-png-250x76.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/neuronnes-it-250x73.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/jcdeceaux-e1645174503841-250x92.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/rte-250x250.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/orpea-250x124.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/Shareweez-Lgogo-1-e1644838315688-250x54.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/hsbc-250x67.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/manymore-250x37.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/ratp-207x250.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/senseee.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                <a>\n                                    <div class=\"partenaires_img my-3 mx-1\" style=\"background-image: url(https:\/\/novelis.io\/wp-content\/uploads\/2022\/02\/siplec-removebg-preview-250x122.png);\"><\/div>\n                                <\/a>\n                            <\/div>\n                                        <\/div>\n            <\/div>\n            <div class=\"d-none d-sm-flex partenaires_swiper_button_next partenaires_swiper_button text-light d-flex align-items-center justify-content-center p-3 display-6\"><i class=\"bi bi-chevron-right d-flex\"><\/i><\/div>\n        <\/div>\n    <\/section>\n\n    <script>\n        partenaires_Swiper();\n    <\/script>\n\n\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a5bed2 elementor-widget elementor-widget-footer\" data-id=\"6a5bed2\" data-element_type=\"widget\" data-widget_type=\"footer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<footer class=\"bg-primary text-light\">\r\n      <div>\r\n        <div class=\"container-fluid p-0\">\r\n          <div class=\"footer_call_to_action d-flex flex-column flex-md-row bg-primary\">\r\n            <a href=\"https:\/\/novelis.io\/fr\/contactez-nous\/\" class=\"background-img-center link-wrapper p-0 w-100 position-relative footer_call_to_action_container contact_img\">\r\n              <div class=\"h-100 w-100 position-absolute\">\r\n\t\t\t          \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204152_20\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/09\/NOVELIS-2000-1DD0-1920x884.jpg\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2025\/09\/NOVELIS-2000-1DD0-30x14.jpg\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204152_20\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t              <\/div>\r\n              <div class=\"opacity-75 h-100 w-100 position-absolute gradient_accent\"><\/div>\r\n              <button class=\"footer-cta-width btn btn-outline-accent-light btn-hover btn-lg position-absolute top-50 start-50 translate-middle text-nowrap\">Contactez-nous<\/button>\r\n            <\/a>\r\n            <a href=\"https:\/\/novelis.io\/fr\/nous-rejoindre\/\" class=\"background-img-center link-wrapper p-0 w-100 position-relative footer_call_to_action_container rojoindre_img\">\r\n              <div class=\"h-100 w-100 position-absolute\">\r\n\t\t\t          \t\t\t<div class=\"loaded-imgs-container\" id=\"img_loader_1778647204154_21\">\n\t\t\t\t<div final-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/05\/group-photo-symposium-morocco.png\" class=\"loaded-imgs\" ><\/div>\n\t\t\t\t<div preload-img=\"https:\/\/novelis.io\/wp-content\/uploads\/2024\/05\/group-photo-symposium-morocco-30x17.png\" class=\"loaded-imgs show-preload-img \" ><\/div>\n\t\t\t\t<script>loadImg(\"img_loader_1778647204154_21\",\"\")<\/script>\n\t\t\t<\/div>\n\t\t              <\/div>\r\n              <div class=\"opacity-75 h-100 w-100 position-relative gradient_secondary\"><\/div>\r\n              <button class=\"footer-cta-width btn btn-outline-secondary-light  btn-hover btn-lg position-absolute top-50 start-50 translate-middle text-nowrap\">Nous rejoindre<\/button>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n\r\n\r\n      <div class=\"footer_email p-4 pb-0 d-flex justify-content-center text-black\">\r\n          <div class=\"pt-4 d-flex email_container newsletter-container\">\r\n            <div class=\"forminator-ui forminator-custom-form forminator-custom-form-3809 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-3809\" data-uid=\"6a0400a425ebc\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-3809\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-3809 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"3809\"\n\t\t\t\t\n\t\t\t\tdata-design=\"default\"\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\tdata-grid=\"open\"\n\t\t\t\t\n\t\t\t\t\n\t\t\t\tstyle=\"display: none;\"\n\t\t\t\t\n\t\t\t\tdata-uid=\"6a0400a425ebc\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-email-1_6a0400a425ebc\" id=\"forminator-field-email-1_6a0400a425ebc-label\" class=\"forminator-label\">Email <span class=\"forminator-required\">*<\/span><\/label><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"Email\" id=\"forminator-field-email-1_6a0400a425ebc\" class=\"forminator-input forminator-email--field\" data-required=\"true\" aria-required=\"true\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"captcha-1\" class=\"forminator-field-captcha forminator-col forminator-col-12 \"><div class=\"forminator-captcha-left forminator-g-recaptcha recaptcha-invisible\" data-theme=\"light\" data-badge=\"bottomright\" data-sitekey=\"6Lc7ejIfAAAAAIRWtX_4nBR59Zsk7_iCcx6KcnI8\" data-size=\"invisible\"><\/div> <\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit btn btn-secondary btn-lg text-nowrap\">S&#039;inscrire &agrave; la Newsletter<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"444a9ab196\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/fr\/wp-json\/wp\/v2\/pages\/3420\" \/><input type=\"hidden\" name=\"form_id\" value=\"3809\"><input type=\"hidden\" name=\"page_id\" value=\"3725\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/novelis.io\/fr\/clients\/siplec\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><label for=\"input_2\" class=\"forminator-hidden\" aria-hidden=\"true\">Veuillez ne pas remplir ce champ. <input id=\"input_2\" type=\"text\" name=\"input_2\" value=\"\" autocomplete=\"off\"><\/label><\/form>          <\/div>\r\n      <\/div>\r\n\r\n      <div class=\"container-xxl row mx-auto footer_content\">\r\n                    \r\n        <div class=\"bd-highlight col-12 col-lg-4 d-flex align-items-center justify-content-lg-center p-lg-5 py-5 position-relative footer_separator\" >\r\n          <a href=\"https:\/\/novelis.io\/fr\/\">\r\n            <div class=\"footer_logo\" style=\"content : url('https:\/\/novelis.io\/wp-content\/uploads\/2021\/12\/light_logo.png')\" ><\/div>\r\n          <\/a>\r\n        <\/div>\r\n        \r\n        <div class=\"bd-highlight col-12 col-lg-4 d-flex align-items-center justify-content-lg-center p-lg-5 py-5 position-relative footer_separator\">\r\n            <ul class=\"row row-cols-2 list-unstyled\">\r\n\r\n\r\n\r\n              \r\n                      <li class=\"col py-1\"><a class=\"text-light underline-hover  \" href=\"https:\/\/novelis.io\/expertise\/\">Services<\/a><\/li>\r\n\r\n              \r\n                      <li class=\"col py-1\"><a class=\"text-light underline-hover  \" href=\"https:\/\/novelis.io\/expertise\/#softwares\">Products<\/a><\/li>\r\n\r\n              \r\n                      <li class=\"col py-1\"><a class=\"text-light underline-hover  \" href=\"https:\/\/novelis.io\/novelis-research-lab\/\">Research Lab<\/a><\/li>\r\n\r\n              \r\n                      <li class=\"col py-1\"><a class=\"text-light underline-hover  \" href=\"https:\/\/novelis.io\/our-news\/\">News<\/a><\/li>\r\n\r\n              \r\n                      <li class=\"col py-1\"><a class=\"text-light underline-hover  \" href=\"https:\/\/novelis.io\/dna\/\">Our DNA<\/a><\/li>\r\n\r\n              \r\n                      <li class=\"col py-1\"><a class=\"text-light underline-hover  \" href=\"https:\/\/novelis.io\/join-us\/\">Join us<\/a><\/li>\r\n\r\n              \r\n                      <li class=\"col py-1\"><a class=\"text-light underline-hover  \" href=\"https:\/\/novelis.io\/contact-us\/\">Contact<\/a><\/li>\r\n\r\n              \r\n            <\/ul>\r\n        <\/div>\r\n        <div class=\"bd-highlight col-12 col-lg-4 d-flex align-items-center justify-content-lg-center p-lg-5 py-5\">\r\n          <ul class=\"list-unstyled\">\r\n            <!-- <li class=\"py-1\"><a href=\"\"><i class=\"bi bi-geo-fill pe-3\"><\/i>207 Rue de Bercy, 75012, Paris<\/a><\/li> -->\r\n           <!--  <li class=\"py-1\"><a href=\"https:\/\/goo.gl\/maps\/SvjwtaGnrs4djV1y7\" class=\"text-light underline-hover\" target=\"_blank\" rel=\"noopener\"><i class=\"bi bi-geo-fill pe-3\"><\/i>Immeuble Lumi\u00e8re, 40 Avenue des Terroirs de France, 75012 Paris, France<\/a><\/li> -->\r\n            \r\n\r\n                              <li class=\"py-1 first-letter-capitalize\"><a href=\"https:\/\/novelis.io\/fr\/mentions-legales\/\" class=\"underline-hover text-light\">Mentions l\u00e9gales<\/a><\/li>\r\n\r\n                              <li class=\"py-1 first-letter-capitalize\"><a href=\"https:\/\/novelis.io\/fr\/politique-de-confidentialite-des-donnees-personnelles\/\" class=\"underline-hover text-light\">Politique de confidentialit\u00e9 des donn\u00e9es personnelles<\/a><\/li>\r\n\r\n                              <li class=\"py-1 first-letter-capitalize\"><a href=\"https:\/\/novelis.io\/fr\/conditions-generales-dutilisation\/\" class=\"underline-hover text-light\">Conditions g\u00e9n\u00e9rales d\u2019utilisation<\/a><\/li>\r\n\r\n            \r\n            <li class='d-flex py-1'>\r\n                                <div class=\"me-3 bd-highlight\"><a href=\"https:\/\/www.linkedin.com\/company\/novelis-consulting\/\" class=\"text-light\" target=\"_blank\" rel=\"noopener\">\r\n\t\t\t\t\t  \t\t\t\t\t  \t<i class=\"bi bi-linkedin\"><\/i>\r\n\t\t\t\t\t  \t\t\t\t\t  <\/a><\/div>\r\n\r\n                                <div class=\"me-3 bd-highlight\"><a href=\"https:\/\/x.com\/novelis_io\" class=\"text-light\">\r\n\t\t\t\t\t  \t\t\t\t\t  <svg width=\"1200\" height=\"1227\" viewBox=\"0 0 1200 1227\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" style=\"\r\n    vertical-align: -.125em;\r\n    height: 1em;\r\n    width: 1em;\r\n\">\r\n<path d=\"M714.163 519.284L1160.89 0H1055.03L667.137 450.887L357.328 0H0L468.492 681.821L0 1226.37H105.866L515.491 750.218L842.672 1226.37H1200L714.137 519.284H714.163ZM569.165 687.828L521.697 619.934L144.011 79.6944H306.615L611.412 515.685L658.88 583.579L1055.08 1150.3H892.476L569.165 687.854V687.828Z\" fill=\"currentColor\"><\/path>\r\n<\/svg>\r\n\t\t\t\t\t  \t\r\n\t\t\t\t\t  \t\t\t\t\t  <\/a><\/div>\r\n\r\n                                <div class=\"me-3 bd-highlight\"><a href=\"https:\/\/www.youtube.com\/channel\/UCJ5eJR22n2GtfKaTWueWRPQ\" class=\"text-light\" target=\"_blank\" rel=\"noopener\">\r\n\t\t\t\t\t  \t\t\t\t\t  \t<i class=\"bi bi-youtube\"><\/i>\r\n\t\t\t\t\t  \t\t\t\t\t  <\/a><\/div>\r\n\r\n              \r\n            <\/li>\r\n            \r\n            <li class=\"py-1 footer-lang\" id=\"wpml-lang-header-footer\">\r\n              <span><i class=\"bi bi-globe\"><\/i><\/span>\r\n              \n<div class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-list-vertical\">\n\t<ul>\n\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item wpml-ls-item-legacy-list-vertical\">\n\t\t\t\t<a href=\"https:\/\/novelis.io\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/novelis.io\/wp-content\/uploads\/flags\/us.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-display\">Anglais<\/span><\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-fr wpml-ls-current-language wpml-ls-item-legacy-list-vertical\">\n\t\t\t\t<a href=\"https:\/\/novelis.io\/fr\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/novelis.io\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/fr.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-native\">Fran\u00e7ais<\/span><\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-de wpml-ls-last-item wpml-ls-item-legacy-list-vertical\">\n\t\t\t\t<a href=\"https:\/\/novelis.io\/de\/\" class=\"wpml-ls-link\">\n                                                        <img decoding=\"async\"\n            class=\"wpml-ls-flag\"\n            src=\"https:\/\/novelis.io\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/de.png\"\n            alt=\"\"\n            width=18\n            height=12\n    \/><span class=\"wpml-ls-display\">Allemand<\/span><\/a>\n\t\t\t<\/li>\n\t\t\n\t<\/ul>\n<\/div>\n            <\/li>\r\n            <script> wpmlGetChoosenLang(\"wpml-lang-header-footer\") <\/script>\r\n\r\n          <\/ul>\r\n        <\/div>\r\n      <\/div>\r\n      <div class=\"container-fluid bg-primaryDark text-center py-3\">\u00a9 2026 Novelis innovation. Tous droits r\u00e9serv\u00e9s.<\/div>\r\n  <\/footer>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Our products SmartRoby\u00ae Novy POM eShadow eSummarize Services Services Intelligent Automation Artificial Intelligence and GenAI Process Intelligence Innovative Architectures Cybersecurity Business Cases Products Products SmartRoby: Your Automation Governance Platform Novy POM: Your Purchase &#038; Order Management Platform eShadow: Your Advanced Document Anonymization Solution eSummarize: Your Precision Summarization Solution Research Lab Novelis Research Lab Vision Solutions [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7230,"parent":0,"menu_order":28,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[254],"custom_tag":[],"class_list":["post-3420","page","type-page","status-publish","has-post-thumbnail","hentry","category-novelis-2"],"acf":{"submenu_navbar_sesond_title":""},"rankMath":{"parentDomain":"novelis.io","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L\u2019image en vedette devrait \u00eatre au moins 200 par 200 pixels pour \u00eatre utilis\u00e9 par Facebook et d\u2019autres sites de m\u00e9dias sociaux.","pluginReviewed":false,"postSettings":{"linkSuggestions":false,"useFocusKeyword":false},"frontEndScore":false,"postName":"siplec","permalinkFormat":"https:\/\/novelis.io\/fr\/clients\/%clients%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/novelis.io\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":false,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"novelis_io","primaryTerm":0,"authorName":"lsalameh","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":true},"homeUrl":"https:\/\/novelis.io\/fr\/","objectID":3725,"objectType":"post","locale":"fr","localeFull":"fr_FR","overlayImages":{"play":{"name":"Ic\u00f4ne de lecture","url":"https:\/\/novelis.io\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhosts\/novelis.io\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Ic\u00f4ne GIF","url":"https:\/\/novelis.io\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhosts\/novelis.io\/httpdocs\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/novelis.io\/wp-content\/uploads\/2025\/08\/novelis-default-social-share-image.png","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fnovelis.io%2Ffr%2F&r=https%3A%2F%2Fnovelis.io%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fpages%2F3420%3Fnonce%3D7cbb8aace5","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/novelis.io\/wp-content\/uploads\/2021\/12\/site_icon.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Mettre \u00e0 niveau","trendsPreviewImage":"https:\/\/novelis.io\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Accueil","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Novelis | L&#039;innovation au service de la performance<\/title>\n<meta name=\"description\" content=\"Novelis | Etre \u00e0 la pointe de la recherche sur l\u2019IA - Architectures innovantes - Efficacit\u00e9 op\u00e9rationnelle des processus m\u00e9tiers\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novelis.io\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novelis | L&#039;innovation au service de la performance\" \/>\n<meta property=\"og:description\" content=\"Novelis | Etre \u00e0 la pointe de la recherche sur l\u2019IA - Architectures innovantes - Efficacit\u00e9 op\u00e9rationnelle des processus m\u00e9tiers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novelis.io\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Novelis innovation\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/novelis.io\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T09:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/novelis.io\/wp-content\/uploads\/2023\/06\/Novelis-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1276\" \/>\n\t<meta property=\"og:image:height\" content=\"957\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@novelis_io\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novelis.io\/fr\/\",\"url\":\"https:\/\/novelis.io\/fr\/\",\"name\":\"Novelis | L'innovation au service de la performance\",\"isPartOf\":{\"@id\":\"https:\/\/novelis.io\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novelis.io\/fr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novelis.io\/fr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/novelis.io\/wp-content\/uploads\/2023\/06\/Novelis-.jpg\",\"datePublished\":\"2021-11-18T15:04:20+00:00\",\"dateModified\":\"2025-10-06T09:42:00+00:00\",\"description\":\"Novelis | Etre \u00e0 la pointe de la recherche sur l\u2019IA - Architectures innovantes - Efficacit\u00e9 op\u00e9rationnelle des processus m\u00e9tiers\",\"breadcrumb\":{\"@id\":\"https:\/\/novelis.io\/fr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novelis.io\/fr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/novelis.io\/fr\/#primaryimage\",\"url\":\"https:\/\/novelis.io\/wp-content\/uploads\/2023\/06\/Novelis-.jpg\",\"contentUrl\":\"https:\/\/novelis.io\/wp-content\/uploads\/2023\/06\/Novelis-.jpg\",\"width\":1276,\"height\":957,\"caption\":\"Novelis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novelis.io\/fr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/novelis.io\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Page d&#8217;accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/novelis.io\/fr\/#website\",\"url\":\"https:\/\/novelis.io\/fr\/\",\"name\":\"Novelis innovation\",\"description\":\"Novelis innovation\",\"publisher\":{\"@id\":\"https:\/\/novelis.io\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/novelis.io\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/novelis.io\/fr\/#organization\",\"name\":\"Novelis innovation\",\"url\":\"https:\/\/novelis.io\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/novelis.io\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/12\/logo-1.png\",\"contentUrl\":\"https:\/\/novelis.io\/wp-content\/uploads\/2021\/12\/logo-1.png\",\"width\":479,\"height\":98,\"caption\":\"Novelis innovation\"},\"image\":{\"@id\":\"https:\/\/novelis.io\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/novelis.io\",\"https:\/\/x.com\/novelis_io\",\"https:\/\/www.linkedin.com\/company\/novelis-consulting\/\",\"https:\/\/www.youtube.com\/channel\/UCJ5eJR22n2GtfKaTWueWRPQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novelis | L'innovation au service de la performance","description":"Novelis | Etre \u00e0 la pointe de la recherche sur l\u2019IA - Architectures innovantes - Efficacit\u00e9 op\u00e9rationnelle des processus m\u00e9tiers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novelis.io\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Novelis | L'innovation au service de la performance","og_description":"Novelis | Etre \u00e0 la pointe de la recherche sur l\u2019IA - Architectures innovantes - Efficacit\u00e9 op\u00e9rationnelle des processus m\u00e9tiers","og_url":"https:\/\/novelis.io\/fr\/","og_site_name":"Novelis innovation","article_publisher":"https:\/\/www.facebook.com\/novelis.io","article_modified_time":"2025-10-06T09:42:00+00:00","og_image":[{"width":1276,"height":957,"url":"https:\/\/novelis.io\/wp-content\/uploads\/2023\/06\/Novelis-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@novelis_io","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/novelis.io\/fr\/","url":"https:\/\/novelis.io\/fr\/","name":"Novelis | L'innovation au service de la performance","isPartOf":{"@id":"https:\/\/novelis.io\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novelis.io\/fr\/#primaryimage"},"image":{"@id":"https:\/\/novelis.io\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/novelis.io\/wp-content\/uploads\/2023\/06\/Novelis-.jpg","datePublished":"2021-11-18T15:04:20+00:00","dateModified":"2025-10-06T09:42:00+00:00","description":"Novelis | Etre \u00e0 la pointe de la recherche sur l\u2019IA - Architectures innovantes - Efficacit\u00e9 op\u00e9rationnelle des processus m\u00e9tiers","breadcrumb":{"@id":"https:\/\/novelis.io\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novelis.io\/fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/novelis.io\/fr\/#primaryimage","url":"https:\/\/novelis.io\/wp-content\/uploads\/2023\/06\/Novelis-.jpg","contentUrl":"https:\/\/novelis.io\/wp-content\/uploads\/2023\/06\/Novelis-.jpg","width":1276,"height":957,"caption":"Novelis"},{"@type":"BreadcrumbList","@id":"https:\/\/novelis.io\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/novelis.io\/fr\/"},{"@type":"ListItem","position":2,"name":"Page d&#8217;accueil"}]},{"@type":"WebSite","@id":"https:\/\/novelis.io\/fr\/#website","url":"https:\/\/novelis.io\/fr\/","name":"Novelis innovation","description":"Novelis innovation","publisher":{"@id":"https:\/\/novelis.io\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novelis.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/novelis.io\/fr\/#organization","name":"Novelis innovation","url":"https:\/\/novelis.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/novelis.io\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/novelis.io\/wp-content\/uploads\/2021\/12\/logo-1.png","contentUrl":"https:\/\/novelis.io\/wp-content\/uploads\/2021\/12\/logo-1.png","width":479,"height":98,"caption":"Novelis innovation"},"image":{"@id":"https:\/\/novelis.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/novelis.io","https:\/\/x.com\/novelis_io","https:\/\/www.linkedin.com\/company\/novelis-consulting\/","https:\/\/www.youtube.com\/channel\/UCJ5eJR22n2GtfKaTWueWRPQ"]}]}},"_links":{"self":[{"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/pages\/3420"}],"collection":[{"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/comments?post=3420"}],"version-history":[{"count":226,"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/pages\/3420\/revisions"}],"predecessor-version":[{"id":11858,"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/pages\/3420\/revisions\/11858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/media\/7230"}],"wp:attachment":[{"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/media?parent=3420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/categories?post=3420"},{"taxonomy":"custom_tag","embeddable":true,"href":"https:\/\/novelis.io\/fr\/wp-json\/wp\/v2\/custom_tag?post=3420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}